{"id":714,"date":"2025-01-20T01:46:43","date_gmt":"2025-01-19T23:46:43","guid":{"rendered":"https:\/\/mam.net.ua\/pediatrics\/?page_id=714"},"modified":"2025-02-22T13:27:50","modified_gmt":"2025-02-22T11:27:50","slug":"xvi","status":"publish","type":"page","link":"https:\/\/mam.net.ua\/pediatrics\/xvi\/","title":{"rendered":"XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"714\" class=\"elementor elementor-714\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e0c20a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e0c20a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bfff534\" data-id=\"bfff534\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7430df2 premium-nav-hor premium-nav-none premium-ham-dropdown elementor-widget elementor-widget-premium-nav-menu\" data-id=\"7430df2\" data-element_type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;fas fa-angle-down&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"premium-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div data-settings=\"{&quot;breakpoint&quot;:1024,&quot;mobileLayout&quot;:&quot;dropdown&quot;,&quot;mainLayout&quot;:&quot;hor&quot;,&quot;stretchDropdown&quot;:false,&quot;hoverEffect&quot;:&quot;&quot;,&quot;submenuEvent&quot;:&quot;hover&quot;,&quot;submenuTrigger&quot;:null}\" class=\"elementor-invisible premium-nav-widget-container premium-nav-pointer-underline premium-nav-animation-fade\">\r\n\t\t\t\t<div class=\"premium-ver-inner-container\">\r\n\t\t\t\t\t<div class=\"premium-hamburger-toggle premium-mobile-menu-icon\" role=\"button\" aria-label=\"Toggle Menu\">\r\n\t\t\t\t\t\t<span class=\"premium-toggle-text\">\r\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bars\"><\/i>Menu\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t<span class=\"premium-toggle-close\">\r\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>Close\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-nav-menu-container premium-nav-default\">\r\n\t\t\t\t\t\t\t\t<ul id=\"menu-%d0%bc%d0%b5%d0%bd%d1%8e-%d0%b4%d0%bb%d1%8f-%d0%b7%d0%b0%d1%85%d0%be%d0%b4%d1%96%d0%b2-ua\" class=\"premium-nav-menu premium-main-nav-menu\"><li id=\"premium-nav-menu-item-331\" class=\"menu-item menu-item-type-custom menu-item-object-custom premium-nav-menu-item\"><a href=\"#organizers\" class=\"premium-menu-link premium-menu-link-parent\">\u041e\u0440\u0433\u0430\u043d\u0456\u0437\u0430\u0442\u043e\u0440\u0438<\/a><\/li>\n<li id=\"premium-nav-menu-item-332\" class=\"menu-item menu-item-type-custom menu-item-object-custom premium-nav-menu-item\"><a href=\"#speakers\" class=\"premium-menu-link premium-menu-link-parent\">\u0415\u043a\u0441\u043f\u0435\u0440\u0442\u0438<\/a><\/li>\n<li id=\"premium-nav-menu-item-333\" class=\"menu-item menu-item-type-custom menu-item-object-custom premium-nav-menu-item\"><a href=\"#program\" class=\"premium-menu-link premium-menu-link-parent\">\u041f\u0440\u043e\u0433\u0440\u0430\u043c\u0430<\/a><\/li>\n<li id=\"premium-nav-menu-item-335\" class=\"menu-item menu-item-type-custom menu-item-object-custom premium-nav-menu-item\"><a href=\"#registration\" class=\"premium-menu-link premium-menu-link-parent\">\u0420\u0435\u0454\u0441\u0442\u0440\u0430\u0446\u0456\u044f<\/a><\/li>\n<li id=\"premium-nav-menu-item-336\" class=\"menu-item menu-item-type-custom menu-item-object-custom premium-nav-menu-item\"><a href=\"#contacts\" class=\"premium-menu-link premium-menu-link-parent\">\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u0438<\/a><\/li>\n<li id=\"premium-nav-menu-item-399\" class=\"menu-item menu-item-type-custom menu-item-object-custom premium-nav-menu-item\"><a href=\"#pll_switcher\" class=\"premium-menu-link premium-menu-link-parent\">\u041c\u043e\u0432\u0438<\/a><\/li>\n<\/ul>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-mobile-menu-container\">\r\n\t\t\t\t\t\t\t\t<ul id=\"menu-%d0%bc%d0%b5%d0%bd%d1%8e-%d0%b4%d0%bb%d1%8f-%d0%b7%d0%b0%d1%85%d0%be%d0%b4%d1%96%d0%b2-ua-1\" class=\"premium-mobile-menu premium-main-mobile-menu premium-main-nav-menu\"><li id=\"premium-nav-menu-item-331\" class=\"menu-item menu-item-type-custom menu-item-object-custom premium-nav-menu-item\"><a href=\"#organizers\" class=\"premium-menu-link premium-menu-link-parent\">\u041e\u0440\u0433\u0430\u043d\u0456\u0437\u0430\u0442\u043e\u0440\u0438<\/a><\/li>\n<li id=\"premium-nav-menu-item-332\" class=\"menu-item menu-item-type-custom menu-item-object-custom premium-nav-menu-item\"><a href=\"#speakers\" class=\"premium-menu-link premium-menu-link-parent\">\u0415\u043a\u0441\u043f\u0435\u0440\u0442\u0438<\/a><\/li>\n<li id=\"premium-nav-menu-item-333\" class=\"menu-item menu-item-type-custom menu-item-object-custom premium-nav-menu-item\"><a href=\"#program\" class=\"premium-menu-link premium-menu-link-parent\">\u041f\u0440\u043e\u0433\u0440\u0430\u043c\u0430<\/a><\/li>\n<li id=\"premium-nav-menu-item-335\" class=\"menu-item menu-item-type-custom menu-item-object-custom premium-nav-menu-item\"><a href=\"#registration\" class=\"premium-menu-link premium-menu-link-parent\">\u0420\u0435\u0454\u0441\u0442\u0440\u0430\u0446\u0456\u044f<\/a><\/li>\n<li id=\"premium-nav-menu-item-336\" class=\"menu-item menu-item-type-custom menu-item-object-custom premium-nav-menu-item\"><a href=\"#contacts\" class=\"premium-menu-link premium-menu-link-parent\">\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u0438<\/a><\/li>\n<li id=\"premium-nav-menu-item-399\" class=\"menu-item menu-item-type-custom menu-item-object-custom premium-nav-menu-item\"><a href=\"#pll_switcher\" class=\"premium-menu-link premium-menu-link-parent\">\u041c\u043e\u0432\u0438<\/a><\/li>\n<\/ul>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7527e23a elementor-section-height-full elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7527e23a\" data-element_type=\"section\" id=\"home\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46e3c576\" data-id=\"46e3c576\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61b0303 text-center elementor-widget elementor-widget-advanced-text-block\" data-id=\"61b0303\" data-element_type=\"widget\" data-widget_type=\"advanced-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"futurio_extra_adv_text_block animate-general\"  data-animate-type=\"transition.fadeIn\" data-animate-delay=\"50\"><h2 class=\"text-content-block\"><p>\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f<\/p><\/div><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-09369bb elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"09369bb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a6796ee\" data-id=\"a6796ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6580b53c elementor-widget elementor-widget-writing-effect-headline\" data-id=\"6580b53c\" data-element_type=\"widget\" data-widget_type=\"writing-effect-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <h3 class=\"futurio-extra-written-headline\" data-speed=\"30\" data-delay=\"1000\" data-loop=\"0\">\r\n                    <span class=\"before-written\">\u0425VI<\/span>\r\n        \r\n                    <span class=\"written-lines\">\u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430<\/span>\r\n        \r\n                <\/h3>\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee98b16 elementor-widget elementor-widget-writing-effect-headline\" data-id=\"ee98b16\" data-element_type=\"widget\" data-widget_type=\"writing-effect-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <h3 class=\"futurio-extra-written-headline\" data-speed=\"30\" data-delay=\"3000\" data-loop=\"0\">\r\n        \r\n                    <span class=\"written-lines\">\u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457<\/span>\r\n        \r\n                <\/h3>\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-58fb294d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58fb294d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5183a0df\" data-id=\"5183a0df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4886141 text-center elementor-widget elementor-widget-advanced-text-block\" data-id=\"4886141\" data-element_type=\"widget\" data-widget_type=\"advanced-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"futurio_extra_adv_text_block \" ><div class=\"text-content-block\"><p>27 \u043b\u044e\u0442\u043e\u0433\u043e - 2 \u0431\u0435\u0440\u0435\u0437\u043d\u044f 2025 \u0440\u043e\u043a\u0443<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4905f53 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4905f53\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-76958f9\" data-id=\"76958f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f982738 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"4f982738\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"#registration\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0420\u0415\u0404\u0421\u0422\u0420\u0410\u0426\u0406\u042f<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f473959\" data-id=\"f473959\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8a1b14 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"e8a1b14\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"#program\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u041f\u0420\u041e\u0413\u0420\u0410\u041c\u0410<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29d27e62 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29d27e62\" data-element_type=\"section\" id=\"services\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4275acad\" data-id=\"4275acad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4305c928 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4305c928\" data-element_type=\"section\" id=\"start\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-53d19cfd\" data-id=\"53d19cfd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-178eb9da elementor-view-stacked elementor-shape-circle elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"178eb9da\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-wobble-horizontal\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\t\u041e\u043d\u043b\u0430\u0439\u043d \u0442\u0440\u0430\u043d\u0441\u043b\u044f\u0446\u0456\u044f\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u0422\u0440\u0430\u043d\u0441\u043b\u044f\u0446\u0456\u044f \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u0457 online, \u0437 \u043c\u043e\u0436\u043b\u0438\u0432\u0456\u0441\u0442\u044e \u043f\u043e\u0432\u0442\u043e\u0440\u043d\u043e\u0433\u043e \u043f\u0435\u0440\u0435\u0433\u043b\u044f\u0434\u0443 \u0443 \u0437\u0430\u043f\u0438\u0441\u0456\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-37baa608\" data-id=\"37baa608\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34337c6e elementor-view-stacked elementor-shape-circle elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"34337c6e\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-wobble-horizontal\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-globe\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\t\u041c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u0456 \u0435\u043a\u0441\u043f\u0435\u0440\u0442\u0438\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u0414\u043e\u0441\u0432\u0456\u0434\u043e\u043c \u0434\u0456\u043b\u044f\u0442\u044c\u0441\u044f \u043f\u0440\u043e\u0432\u0456\u0434\u043d\u0456 \u0441\u043f\u0435\u0446\u0456\u0430\u043b\u0456\u0441\u0442\u0438 \u0437 \u0423\u043a\u0440\u0430\u0457\u043d\u0438, \u043a\u0440\u0430\u0457\u043d \u0404\u0421 \u0442\u0430 \u0421\u0428\u0410\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3968b6ab\" data-id=\"3968b6ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32dd7d49 elementor-view-stacked elementor-shape-circle elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"32dd7d49\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-wobble-horizontal\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chalkboard-teacher\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\t\u041d\u0430\u0441\u0438\u0447\u0435\u043d\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0430\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u041d\u0430 \u0432\u0430\u0441 \u0447\u0435\u043a\u0430\u044e\u0442\u044c \u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0440\u0435\u043a\u043e\u043c\u0435\u043d\u0442\u0430\u0446\u0456\u0457, \u0440\u043e\u0437\u0431\u0456\u0440 \u043a\u043b\u0456\u043d\u0456\u0447\u043d\u0438\u0445 \u0432\u0438\u043f\u0430\u0434\u043a\u0456\u0432, \u043c\u0430\u0439\u0441\u0442\u0435\u0440-\u043a\u043b\u0430\u0441\u0438 \u0442\u0430 \u0442\u0440\u0435\u043d\u0456\u043d\u0433\u0438\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4297811a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4297811a\" data-element_type=\"section\" id=\"about\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;mountains&quot;,&quot;shape_divider_bottom&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d25e7a5\" data-id=\"6d25e7a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3d3e9bcc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d3e9bcc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2c2cb51e\" data-id=\"2c2cb51e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a4d874 text-center elementor-widget elementor-widget-advanced-text-block\" data-id=\"7a4d874\" data-element_type=\"widget\" data-widget_type=\"advanced-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"futurio_extra_adv_text_block animate-general\"  data-animate-type=\"transition.fadeIn\" data-animate-delay=\"50\"><h2 class=\"text-content-block\"><p>\u041d\u0430\u0443\u043a\u043e\u0432\u0438\u0439 \u043a\u0435\u0440\u0456\u0432\u043d\u0438\u043a<\/p><\/div><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c87a3ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c87a3ee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0661428\" data-id=\"0661428\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b415ebf elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b415ebf\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.1 - 17-01-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h1><b>\u0411\u0435\u043a\u0435\u0442\u043e\u0432\u0430 \u0413\u0430\u043b\u0438\u043d\u0430 \u0412\u043e\u043b\u043e\u0434\u0438\u043c\u0438\u0440\u0456\u0432\u043d\u0430\u00a0<\/b><\/h1><p>\u0434\u043e\u043a\u0442\u043e\u0440 \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0445 \u043d\u0430\u0443\u043a,<br \/>\u043f\u0440\u043e\u0444\u0435\u0441\u043e\u0440,<br \/>\u0437\u0430\u0441\u043b\u0443\u0436\u0435\u043d\u0438\u0439 \u043b\u0456\u043a\u0430\u0440 \u0423\u043a\u0440\u0430\u0457\u043d\u0438,<br \/>\u0447\u043b\u0435\u043d-\u043a\u043e\u0440\u0435\u0441\u043f\u043e\u043d\u0434\u0435\u043d\u0442 \u041d\u0410\u041c\u041d \u0423\u043a\u0440\u0430\u0457\u043d\u0438,<br \/>\u0437\u0430\u0432\u0456\u0434\u0443\u0432\u0430\u0447 \u043a\u0430\u0444\u0435\u0434\u0440\u0438 \u0434\u0438\u0442\u044f\u0447\u0438\u0445 \u0456 \u043f\u0456\u0434\u043b\u0456\u0442\u043a\u043e\u0432\u0438\u0445 \u0437\u0430\u0445\u0432\u043e\u0440\u044e\u0432\u0430\u043d\u044c \u041d\u0430\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442\u0443<br \/>\u043e\u0445\u043e\u0440\u043e\u043d\u0438 \u0437\u0434\u043e\u0440\u043e\u0432\u2019\u044f \u0423\u043a\u0440\u0430\u0457\u043d\u0438 \u0456\u043c. \u041f. \u041b. \u0428\u0443\u043f\u0438\u043a\u0430<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7ae9dcd\" data-id=\"7ae9dcd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f363776 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"f363776\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.1 - 17-01-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"463\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/Beketova.jpg\" class=\"attachment-medium_large size-medium_large wp-image-290\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/Beketova.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/Beketova-194x300.jpg 194w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-315a4caa elementor-section-height-min-height elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"315a4caa\" data-element_type=\"section\" id=\"organizers\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1171289d\" data-id=\"1171289d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33860e0 text-center elementor-widget elementor-widget-advanced-text-block\" data-id=\"33860e0\" data-element_type=\"widget\" data-widget_type=\"advanced-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"futurio_extra_adv_text_block \" ><h2 class=\"text-content-block\"><p>\u041e\u0420\u0413\u0410\u041d\u0406\u0417\u0410\u0422\u041e\u0420\u0418<\/p><\/div><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-41f0bfd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41f0bfd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-073c672 elementor-invisible\" data-id=\"073c672\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1133e171 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"1133e171\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.1 - 17-01-2023 *\/\n.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:right;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:left;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/mam-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/mam-150x150.png 150w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/mam.png 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">\u0413\u041e \u00ab\u041c\u0406\u0416\u041d\u0410\u0420\u041e\u0414\u041d\u0410 \u0410\u0421\u041e\u0426\u0406\u0410\u0426\u0406\u042f \u041c\u0415\u0414\u0418\u0426\u0418\u041d\u0418\u00bb<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-08cd248 elementor-invisible\" data-id=\"08cd248\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2388109a elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"2388109a\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/02\/\u041d\u0410\u041c\u041d-\u0423\u043a\u0440\u0430\u0457\u043d\u0438-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-666\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/02\/\u041d\u0410\u041c\u041d-\u0423\u043a\u0440\u0430\u0457\u043d\u0438-150x150.png 150w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/02\/\u041d\u0410\u041c\u041d-\u0423\u043a\u0440\u0430\u0457\u043d\u0438.png 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">\u041d\u0430\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u0430 \u0430\u043a\u0430\u0434\u0435\u043c\u0456\u044f \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0445 \u043d\u0430\u0443\u043a \u0423\u043a\u0440\u0430\u0457\u043d\u0438 <\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a6aa1ae elementor-invisible\" data-id=\"a6aa1ae\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5edd4182 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"5edd4182\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/\u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0432-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-297\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/\u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0432-150x150.png 150w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/\u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0432.png 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">\u0410\u0421\u041e\u0426\u0406\u0410\u0426\u0406\u042f \u041f\u0415\u0414\u0406\u0410\u0422\u0420\u0406\u0412<br> \u041c. \u041a\u0418\u0404\u0412\u0410<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4c4231c elementor-invisible\" data-id=\"4c4231c\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23fef1e5 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"23fef1e5\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/\u043e\u0445\u043e\u0440\u043e\u043d\u0438-\u0437\u0434\u043e\u0440\u043e\u0432\u044f-\u0423\u043a\u0440\u0430\u0457\u043d\u0438-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-295\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/\u043e\u0445\u043e\u0440\u043e\u043d\u0438-\u0437\u0434\u043e\u0440\u043e\u0432\u044f-\u0423\u043a\u0440\u0430\u0457\u043d\u0438-150x150.png 150w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/\u043e\u0445\u043e\u0440\u043e\u043d\u0438-\u0437\u0434\u043e\u0440\u043e\u0432\u044f-\u0423\u043a\u0440\u0430\u0457\u043d\u0438.png 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">\u041c\u0406\u041d\u0406\u0421\u0422\u0415\u0420\u0421\u0422\u0412\u041e \u041e\u0425\u041e\u0420\u041e\u041d\u0418 \u0417\u0414\u041e\u0420\u041e\u0412'\u042f \u0423\u041a\u0420\u0410\u0407\u041d\u0418<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7520ea5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7520ea5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-14b4241\" data-id=\"14b4241\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5ec2ae elementor-widget elementor-widget-heading\" data-id=\"b5ec2ae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.1 - 17-01-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">\u0421\u0435\u0440\u0442\u0438\u0444\u0456\u043a\u0430\u0446\u0456\u044f \u0411\u041f\u0420<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f7d5c8 elementor-widget elementor-widget-text-editor\" data-id=\"1f7d5c8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u0417\u0430\u0445\u0456\u0434 \u0441\u0435\u0440\u0442\u0438\u0444\u0456\u043a\u043e\u0432\u0430\u043d\u0438\u0439 \u0426\u0435\u043d\u0442\u0440\u043e\u043c \u0442\u0435\u0441\u0442\u0443\u0432\u0430\u043d\u043d\u044f \u0411\u041f\u0420<\/strong><\/p><p>\u041f\u0456\u0441\u043b\u044f \u0437\u0430\u0432\u0435\u0440\u0448\u0435\u043d\u043d\u044f \u0437\u0430\u0445\u043e\u0434\u0443 \u043a\u043e\u0436\u0435\u043d \u0443\u0447\u0430\u0441\u043d\u0438\u043a \u043e\u0442\u0440\u0438\u043c\u0430\u0454 \u0441\u0435\u0440\u0442\u0438\u0444\u0456\u043a\u0430\u0442 \u0437 \u0431\u0430\u043b\u0430\u043c\u0438 \u043f\u0440\u043e \u0443\u0447\u0430\u0441\u0442\u044c \u0443 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u0457 (\u0437\u0430 \u0443\u043c\u043e\u0432\u0438 \u0443\u0441\u043f\u0456\u0448\u043d\u043e\u0433\u043e \u043f\u0440\u043e\u0445\u043e\u0434\u0436\u0435\u043d\u043d\u044f \u043e\u043d\u043b\u0430\u0439\u043d-\u0442\u0435\u0441\u0442\u0443\u0432\u0430\u043d\u043d\u044f \u043f\u043e\u043d\u0430\u0434 60% \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u0438\u0445 \u0432\u0456\u0434\u043f\u043e\u0432\u0456\u0434\u0435\u0439)<br \/><strong>\u0412\u0410\u0416\u041b\u0418\u0412\u041e: \u0434\u043b\u044f \u043e\u0442\u0440\u0438\u043c\u0430\u043d\u043d\u044f \u0431\u0430\u043b\u0456\u0432 \u043d\u0435\u043e\u0431\u0445\u0456\u0434\u043d\u043e \u0437\u0430\u0440\u0435\u0454\u0441\u0442\u0440\u0443\u0432\u0430\u0442\u0438\u0441\u044c \u043d\u0430 \u0434\u0432\u0430 \u0437\u0430\u0445\u043e\u0434\u0438 (\u041d\u041f\u041a \u0442\u0430 \u041c\u041a) \u0442\u0430 \u0443\u0441\u043f\u0456\u0448\u043d\u043e \u0441\u043a\u043b\u0430\u0441\u0442\u0438 \u043e\u0431\u0438\u0434\u0432\u0430 \u0442\u0435\u0441\u0442\u0443\u0432\u0430\u043d\u043d\u044f<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5256dc3 elementor-widget elementor-widget-accordion\" data-id=\"5256dc3\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.1 - 17-01-2023 *\/\n.elementor-accordion{text-align:left}.elementor-accordion .elementor-accordion-item{border:1px solid #d4d4d4}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d4d4d4}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8631\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-8631\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">\u041f\u0435\u0440\u0435\u043b\u0456\u043a \u043b\u0456\u043a\u0430\u0440\u0441\u044c\u043a\u0438\u0445 \u0441\u043f\u0435\u0446\u0456\u0430\u043b\u044c\u043d\u043e\u0441\u0442\u0435\u0439, \u0449\u043e \u0437\u043c\u043e\u0436\u0443\u0442\u044c \u043e\u0442\u0440\u0438\u043c\u0430\u0442\u0438 \u0441\u0435\u0440\u0442\u0438\u0444\u0456\u043a\u0430\u0442 \u0443\u0447\u0430\u0441\u043d\u0438\u043a\u0430 \u041d\u041f\u041a<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8631\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8631\"><p>\u0410\u043b\u0435\u0440\u0433\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0411\u0430\u043a\u0442\u0435\u0440\u0456\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0412\u0456\u0440\u0443\u0441\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0413\u0430\u0441\u0442\u0440\u043e\u0435\u043d\u0442\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0413\u0456\u0433\u0456\u0454\u043d\u0430 \u0434\u0456\u0442\u0435\u0439 \u0442\u0430 \u043f\u0456\u0434\u043b\u0456\u0442\u043a\u0456\u0432<br \/>\u0413\u0456\u0433\u0456\u0454\u043d\u0430 \u043f\u0440\u0430\u0446\u0456<br \/>\u0413\u0456\u0433\u0456\u0454\u043d\u0430 \u0445\u0430\u0440\u0447\u0443\u0432\u0430\u043d\u043d\u044f<br \/>\u0414\u0435\u0437\u0456\u043d\u0444\u0435\u043a\u0446\u0456\u0439\u043d\u0430 \u0441\u043f\u0440\u0430\u0432\u0430<br \/>\u0414\u0435\u0440\u043c\u0430\u0442\u043e\u0432\u0435\u043d\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0430\u043b\u0435\u0440\u0433\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0430\u043d\u0435\u0441\u0442\u0435\u0437\u0456\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0433\u0430\u0441\u0442\u0440\u043e\u0435\u043d\u0442\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0433\u0456\u043d\u0435\u043a\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0434\u0435\u0440\u043c\u0430\u0442\u043e\u0432\u0435\u043d\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0435\u043d\u0434\u043e\u043a\u0440\u0438\u043d\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0456\u043c\u0443\u043d\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043a\u0430\u0440\u0434\u0456\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043d\u0435\u0432\u0440\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043d\u0435\u0444\u0440\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043e\u0440\u0442\u043e\u043f\u0435\u0434\u0456\u044f \u0456 \u0442\u0440\u0430\u0432\u043c\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043e\u0442\u043e\u043b\u0430\u0440\u0438\u043d\u0433\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043e\u0444\u0442\u0430\u043b\u044c\u043c\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043f\u0441\u0438\u0445\u0456\u0430\u0442\u0440\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043f\u0443\u043b\u044c\u043c\u043e\u043d\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0445\u0456\u0440\u0443\u0440\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0456 \u0456\u043d\u0444\u0435\u043a\u0446\u0456\u0439\u043d\u0456 \u0445\u0432\u043e\u0440\u043e\u0431\u0438<br \/>\u0414\u0456\u0454\u0442\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0415\u043d\u0434\u043e\u043a\u0440\u0438\u043d\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0417\u0430\u0433\u0430\u043b\u044c\u043d\u0430 \u0433\u0456\u0433\u0456\u0454\u043d\u0430<br \/>\u0417\u0430\u0433\u0430\u043b\u044c\u043d\u0430 \u043f\u0440\u0430\u043a\u0442\u0438\u043a\u0430 &#8211; \u0441\u0456\u043c\u0435\u0439\u043d\u0430 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0430<br \/>\u0406\u043d\u0444\u0435\u043a\u0446\u0456\u0439\u043d\u0456 \u0445\u0432\u043e\u0440\u043e\u0431\u0438<br \/>\u041b\u0430\u0431\u043e\u0440\u0430\u0442\u043e\u0440\u043d\u0456 \u0434\u043e\u0441\u043b\u0456\u0434\u0436\u0435\u043d\u043d\u044f \u0444\u0430\u043a\u0442\u043e\u0440\u0456\u0432 \u043d\u0430\u0432\u043a\u043e\u043b\u0438\u0448\u043d\u044c\u043e\u0433\u043e \u0441\u0435\u0440\u0435\u0434\u043e\u0432\u0438\u0449\u0430<br \/>\u041c\u0435\u0434\u0438\u0446\u0438\u043d\u0430 \u043d\u0435\u0432\u0456\u0434\u043a\u043b\u0430\u0434\u043d\u0438\u0445 \u0441\u0442\u0430\u043d\u0456\u0432<br \/>\u041e\u0440\u0433\u0430\u043d\u0456\u0437\u0430\u0446\u0456\u044f \u0456 \u0443\u043f\u0440\u0430\u0432\u043b\u0456\u043d\u043d\u044f \u043e\u0445\u043e\u0440\u043e\u043d\u043e\u044e \u0437\u0434\u043e\u0440\u043e\u0432\u2019\u044f<br \/>\u041f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u044f<br \/>\u041f\u0441\u0438\u0445\u0456\u0430\u0442\u0440\u0456\u044f<br \/>\u041f\u0441\u0438\u0445\u043e\u0442\u0435\u0440\u0430\u043f\u0456\u044f<br \/>\u041f\u0443\u043b\u044c\u043c\u043e\u043d\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0424\u0443\u043d\u043a\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u0430 \u0434\u0456\u0430\u0433\u043d\u043e\u0441\u0442\u0438\u043a\u0430<br \/>\u0412\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u0456 \u0445\u0432\u043e\u0440\u043e\u0431\u0438<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8632\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"tab\" aria-controls=\"elementor-tab-content-8632\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">\u041f\u0435\u0440\u0435\u043b\u0456\u043a \u043b\u0456\u043a\u0430\u0440\u0441\u044c\u043a\u0438\u0445 \u0441\u043f\u0435\u0446\u0456\u0430\u043b\u044c\u043d\u043e\u0441\u0442\u0435\u0439, \u0449\u043e \u0437\u043c\u043e\u0436\u0443\u0442\u044c \u043e\u0442\u0440\u0438\u043c\u0430\u0442\u0438 \u0441\u0435\u0440\u0442\u0438\u0444\u0456\u043a\u0430\u0442 \u0443\u0447\u0430\u0441\u043d\u0438\u043a\u0430 \u043c\u0430\u0439\u0441\u0442\u0435\u0440-\u043a\u043b\u0430\u0441\u0443<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8632\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8632\"><p>\u041f\u0440\u043e\u0444\u0435\u0441\u0456\u043e\u043d\u0430\u043b\u0438 \u0437 \u0432\u0438\u0449\u043e\u044e \u043d\u0435\u043c\u0435\u0434\u0438\u0447\u043d\u043e\u044e \u043e\u0441\u0432\u0456\u0442\u043e\u044e, \u044f\u043a\u0456 \u043f\u0440\u0430\u0446\u044e\u044e\u0442\u044c \u0432 \u0441\u0438\u0441\u0442\u0435\u043c\u0456 \u043e\u0445\u043e\u0440\u043e\u043d\u0438 \u0437\u0434\u043e\u0440\u043e\u0432\u2019\u044f<br \/>\u0421\u043f\u0435\u0446\u0456\u0430\u043b\u044c\u043d\u043e\u0441\u0442\u0456 \u043c\u043e\u043b\u043e\u0434\u0448\u0438\u0445 \u0441\u043f\u0435\u0446\u0456\u0430\u043b\u0456\u0441\u0442\u0456\u0432 \u0437 \u043c\u0435\u0434\u0438\u0447\u043d\u043e\u044e \u043e\u0441\u0432\u0456\u0442\u043e\u044e<br \/>\u0411\u0430\u043a\u0442\u0435\u0440\u0456\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0412\u0456\u0440\u0443\u0441\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0413\u0430\u0441\u0442\u0440\u043e\u0435\u043d\u0442\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0435\u0437\u0456\u043d\u0444\u0435\u043a\u0446\u0456\u0439\u043d\u0430 \u0441\u043f\u0440\u0430\u0432\u0430<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0430\u043b\u0435\u0440\u0433\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0430\u043d\u0435\u0441\u0442\u0435\u0437\u0456\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0433\u0430\u0441\u0442\u0440\u043e\u0435\u043d\u0442\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0434\u0435\u0440\u043c\u0430\u0442\u043e\u0432\u0435\u043d\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0435\u043d\u0434\u043e\u043a\u0440\u0438\u043d\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0456\u043c\u0443\u043d\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043a\u0430\u0440\u0434\u0456\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043d\u0435\u0432\u0440\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043d\u0435\u0439\u0440\u043e\u0445\u0456\u0440\u0443\u0440\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043d\u0435\u0444\u0440\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043e\u0440\u0442\u043e\u043f\u0435\u0434\u0456\u044f \u0456 \u0442\u0440\u0430\u0432\u043c\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043e\u0442\u043e\u043b\u0430\u0440\u0438\u043d\u0433\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043e\u0444\u0442\u0430\u043b\u044c\u043c\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043f\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u0447\u043d\u0430 \u0430\u043d\u0430\u0442\u043e\u043c\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043f\u0441\u0438\u0445\u0456\u0430\u0442\u0440\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u043f\u0443\u043b\u044c\u043c\u043e\u043d\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0440\u0435\u0432\u043c\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0443\u0440\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0444\u0442\u0438\u0437\u0456\u0430\u0442\u0440\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0430 \u0445\u0456\u0440\u0443\u0440\u0433\u0456\u044f<br \/>\u0414\u0438\u0442\u044f\u0447\u0456 \u0456\u043d\u0444\u0435\u043a\u0446\u0456\u0439\u043d\u0456 \u0445\u0432\u043e\u0440\u043e\u0431\u0438<br \/>\u0414\u0456\u0454\u0442\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u0417\u0430\u0433\u0430\u043b\u044c\u043d\u0430 \u0433\u0456\u0433\u0456\u0454\u043d\u0430<br \/>\u0417\u0430\u0433\u0430\u043b\u044c\u043d\u0430 \u043f\u0440\u0430\u043a\u0442\u0438\u043a\u0430 &#8211; \u0441\u0456\u043c\u0435\u0439\u043d\u0430 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0430<br \/>\u0406\u043d\u0444\u0435\u043a\u0446\u0456\u0439\u043d\u0456 \u0445\u0432\u043e\u0440\u043e\u0431\u0438<br \/>\u041b\u0430\u0431\u043e\u0440\u0430\u0442\u043e\u0440\u043d\u0456 \u0434\u043e\u0441\u043b\u0456\u0434\u0436\u0435\u043d\u043d\u044f \u0444\u0430\u043a\u0442\u043e\u0440\u0456\u0432 \u043d\u0430\u0432\u043a\u043e\u043b\u0438\u0448\u043d\u044c\u043e\u0433\u043e \u0441\u0435\u0440\u0435\u0434\u043e\u0432\u0438\u0449\u0430<br \/>\u041c\u0435\u0434\u0438\u0446\u0438\u043d\u0430 \u043d\u0435\u0432\u0456\u0434\u043a\u043b\u0430\u0434\u043d\u0438\u0445 \u0441\u0442\u0430\u043d\u0456\u0432<br \/>\u041d\u0435\u0432\u0440\u043e\u043b\u043e\u0433\u0456\u044f<br \/>\u041f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u044f<br \/>\u0424\u0456\u0437\u0438\u0447\u043d\u0430 \u0442\u0430 \u0440\u0435\u0430\u0431\u0456\u043b\u0456\u0442\u0430\u0446\u0456\u0439\u043d\u0430 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0430<br \/>\u0412\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u0456 \u0445\u0432\u043e\u0440\u043e\u0431\u0438<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-984df1c elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"984df1c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"#registration\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0420\u0415\u0404\u0421\u0422\u0420\u0410\u0426\u0406\u042f \u043d\u0430 \u0448\u043a\u043e\u043b\u0443 <\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c2d067 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"9c2d067\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/mam.net.ua\/ua\/kalendar\/event\/275-maister-klas-nutrytyvnyi-suprovid-zakhvoriuvan-v-pediatrii-mozhlyvosti-ta-pomylky\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0420\u0415\u0404\u0421\u0422\u0420\u0410\u0426\u0406\u042f \u043d\u0430 \u043c\u0430\u0439\u0441\u0442\u0435\u0440-\u043a\u043b\u0430\u0441<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38254409 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38254409\" data-element_type=\"section\" id=\"speakers\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b42030c\" data-id=\"7b42030c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc638f0 text-center elementor-widget elementor-widget-advanced-text-block\" data-id=\"fc638f0\" data-element_type=\"widget\" data-widget_type=\"advanced-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"futurio_extra_adv_text_block \" ><h2 class=\"text-content-block\"><p>\u041c\u0406\u0416\u041d\u0410\u0420\u041e\u0414\u041d\u0406 \u0415\u041a\u0421\u041f\u0415\u0420\u0422\u0418<\/p><\/div><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e232a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e232a8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cdba994\" data-id=\"cdba994\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b250c0a elementor-position-right elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"b250c0a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/mam.net.ua\/pediatricsXI\/wp-content\/uploads\/2022\/10\/Foto_4-1.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Rimantas Kevalas<\/h3><p class=\"elementor-image-box-description\">Prof., \u0433\u043e\u043b\u043e\u0432\u0430 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0438\u0447\u043d\u043e\u0457 \u043a\u043b\u0456\u043d\u0456\u043a\u0438 \u0456 \u0432\u0456\u0434\u0434\u0456\u043b\u0435\u043d\u043d\u044f \u0434\u0438\u0442\u044f\u0447\u043e\u0457 \u043d\u0435\u0432\u0456\u0434\u043a\u043b\u0430\u0434\u043d\u043e\u0457 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0438, \u041b\u0438\u0442\u043e\u0432\u0441\u044c\u043a\u0438\u0439 \u0443\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442 \u043d\u0430\u0443\u043a \u0437\u0434\u043e\u0440\u043e\u0432\u2019\u044f, \u0435\u043a\u0441\u043f\u0435\u0440\u0442 \u042e\u041d\u0406\u0421\u0415\u0424 \u0432 \u0441\u0444\u0435\u0440\u0456 \u043d\u0435\u0432\u0456\u0434\u043a\u043b\u0430\u0434\u043d\u043e\u0457 \u043c\u0435\u0434\u0438\u0447\u043d\u043e\u0457 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0438 \u0442\u0430 \u0442\u0440\u0430\u043d\u0441\u043f\u043e\u0440\u0442\u0443\u0432\u0430\u043d\u043d\u044f \u0434\u0456\u0442\u0435\u0439, Lithuania<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8e55d6f\" data-id=\"8e55d6f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a07ea0f elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"a07ea0f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/mam.net.ua\/pediatricsX\/wp-content\/uploads\/2022\/02\/Gerbaud_Laurent_1.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Gerbaud Laurent <\/h3><p class=\"elementor-image-box-description\">MD, PhD, France<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d2052cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2052cc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-32ff570\" data-id=\"32ff570\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5bd054 elementor-position-right elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"a5bd054\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/\u0420\u0435\u0432\u0435\u043d\u043a\u043e-\u041d\u0438\u043d\u0435\u043b\u044c.jpg\" class=\"attachment-full size-full wp-image-303\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/\u0420\u0435\u0432\u0435\u043d\u043a\u043e-\u041d\u0438\u043d\u0435\u043b\u044c.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/\u0420\u0435\u0432\u0435\u043d\u043a\u043e-\u041d\u0438\u043d\u0435\u043b\u044c-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0420\u0435\u0432\u0435\u043d\u043a\u043e \u041d\u0456\u043d\u0435\u043b\u044c <\/h3><p class=\"elementor-image-box-description\">\u041f\u0440\u043e\u0444\u0435\u0441\u043e\u0440, \u0434\u043e\u043a\u0442\u043e\u0440 \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0445 \u043d\u0430\u0443\u043a, \u0437\u0430\u0432\u0456\u0434\u0443\u044e\u0447\u0430 \u0414\u0435\u043f\u0430\u0440\u0442\u0430\u043c\u0435\u043d\u0442\u043e\u043c \u041f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457 \u0413\u0423\u041c\u0424 \u041d\u0438\u043a\u043e\u043b\u0430\u0435 \u0422\u0435\u0441\u0442\u0435\u043c\u0438\u0446\u0430\u043d\u0443, \u0433\u043e\u043b\u043e\u0432\u0430 \u0422\u043e\u0432\u0430\u0440\u0438\u0441\u0442\u0432\u0430 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0432 \u0420\u0435\u0441\u043f\u0443\u0431\u043b\u0456\u043a\u0438 \u041c\u043e\u043b\u0434\u043e\u0432\u0430<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d0fb68f\" data-id=\"d0fb68f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbffcc0 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"dbffcc0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Andre-LABBE\u200b-300x300.jpg\" class=\"attachment-medium size-medium wp-image-403\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Andre-LABBE\u200b.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Andre-LABBE\u200b-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"> Andr\u00e9 LABBE<\/h3><p class=\"elementor-image-box-description\">MD, PhD, France<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-90a5409 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"90a5409\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a64d5a8\" data-id=\"a64d5a8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eaf4adb elementor-position-right elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"eaf4adb\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Martin-Kneyber.jpg\" class=\"attachment-full size-full wp-image-401\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Martin-Kneyber.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Martin-Kneyber-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"> Martin Kneijber<\/h3><p class=\"elementor-image-box-description\"> MD Ph FCCM, Netherlands<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5049fe3\" data-id=\"5049fe3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b83404 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"9b83404\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Anthony-Fardet-300x300.jpg\" class=\"attachment-medium size-medium wp-image-407\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Anthony-Fardet.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Anthony-Fardet-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Anthony Fardet<\/h3><p class=\"elementor-image-box-description\">PhD, \u0441\u0442\u0430\u0440\u0448\u0438\u0439 \u043d\u0430\u0443\u043a\u043e\u0432\u0438\u0439 \u0441\u043f\u0456\u0432\u0440\u043e\u0431\u0456\u0442\u043d\u0438\u043a INRAE, France\n<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d6fcf54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6fcf54\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-08ddeb6\" data-id=\"08ddeb6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecdfa46 elementor-position-right elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"ecdfa46\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Chung-Sandy.jpg\" class=\"attachment-full size-full wp-image-402\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Chung-Sandy.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Chung-Sandy-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sandy Chung<\/h3><p class=\"elementor-image-box-description\">MD, FAAP, USA<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c0bf424\" data-id=\"c0bf424\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9357b97 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"9357b97\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Jobayer-Chisti\u200b-300x300.jpg\" class=\"attachment-medium size-medium wp-image-408\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Jobayer-Chisti\u200b.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Jobayer-Chisti\u200b-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Jobayer Chisti<\/h3><p class=\"elementor-image-box-description\">MD, MBBS, MMed, PhD, Bangladesh<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a3ff5f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3ff5f1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c4affbd\" data-id=\"c4affbd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad81779 elementor-position-right elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"ad81779\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Tiziano-Barbui\u200b.jpg\" class=\"attachment-full size-full wp-image-423\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Tiziano-Barbui\u200b.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Tiziano-Barbui\u200b-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Tiziano Barbui<\/h3><p class=\"elementor-image-box-description\">MD, PhD, Italy<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9f2b63e\" data-id=\"9f2b63e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f79b3ba elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f79b3ba\" data-element_type=\"section\" id=\"speakers\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a5d6d3\" data-id=\"0a5d6d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d49c925 text-center elementor-widget elementor-widget-advanced-text-block\" data-id=\"d49c925\" data-element_type=\"widget\" data-widget_type=\"advanced-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"futurio_extra_adv_text_block \" ><h3 class=\"text-content-block\"><p>\u041c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u0456 \u0435\u043a\u0441\u043f\u0435\u0440\u0442\u0438<\/p><\/div><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6529cb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6529cb7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-388b20e\" data-id=\"388b20e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-07c4ab9\" data-id=\"07c4ab9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96a4455 elementor-widget elementor-widget-premium-addon-person\" data-id=\"96a4455\" data-element_type=\"widget\" data-widget_type=\"premium-addon-person.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"premium-persons-container premium-person-style2\">\r\n\t\t\t\t\t\t<div class=\"premium-person-container premium-person-none-effect\">\r\n\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1417\" height=\"1417\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/Rimantas-Kevalas.jpg\" class=\"attachment-full size-full wp-image-622\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/Rimantas-Kevalas.jpg 1417w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/Rimantas-Kevalas-300x300.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/Rimantas-Kevalas-1024x1024.jpg 1024w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/Rimantas-Kevalas-150x150.jpg 150w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/Rimantas-Kevalas-768x768.jpg 768w\" sizes=\"auto, (max-width: 1417px) 100vw, 1417px\" \/>\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-social\">\r\n\t\t\t\t\t\t\t<ul class=\"premium-person-social-list\">\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-facebook\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-facebook-f\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-twitter\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-twitter\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-instagram\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-instagram\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-dribbble\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-dribbble\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t<\/ul>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<h2 class=\"premium-person-name\">\r\n\t\t\t\t\t\tRimantas Kevalas\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"premium-person-title\">\r\n\t\t\t\t\t\t\t<span>\u041b\u0438\u0442\u0432\u0430<\/span>\r\n\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p>\u043f\u0440\u043e\u0444\u0435\u0441\u043e\u0440, \u0433\u043e\u043b\u043e\u0432\u0430 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0438\u0447\u043d\u043e\u0457 \u043a\u043b\u0456\u043d\u0456\u043a\u0438 \u0456 \u0432\u0456\u0434\u0434\u0456\u043b\u0435\u043d\u043d\u044f \u0434\u0438\u0442\u044f\u0447\u043e\u0457 \u043d\u0435\u0432\u0456\u0434\u043a\u043b\u0430\u0434\u043d\u043e\u0457 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0438, \u041b\u0438\u0442\u043e\u0432\u0441\u044c\u043a\u0438\u0439 \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442 \u043d\u0430\u0443\u043a \u0437\u0434\u043e\u0440\u043e\u0432\u2019\u044f, \u0435\u043a\u0441\u043f\u0435\u0440\u0442 \u042e\u041d\u0406\u0421\u0415\u0424 \u0432 \u0441\u0444\u0435\u0440\u0456 \u043d\u0435\u0432\u0456\u0434\u043a\u043b\u0430\u0434\u043d\u043e\u0457 \u043c\u0435\u0434\u0438\u0447\u043d\u043e\u0457 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0438 \u0442\u0430 \u0442\u0440\u0430\u043d\u0441\u043f\u043e\u0440\u0442\u0443\u0432\u0430\u043d\u043d\u044f \u0434\u0456\u0442\u0435\u0439<\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d711e2a\" data-id=\"d711e2a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf763b7 elementor-widget elementor-widget-premium-addon-person\" data-id=\"cf763b7\" data-element_type=\"widget\" data-widget_type=\"premium-addon-person.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"premium-persons-container premium-person-style2\">\r\n\t\t\t\t\t\t<div class=\"premium-person-container premium-person-none-effect\">\r\n\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/Anthony-Fardet.jpg\" class=\"attachment-full size-full wp-image-625\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/Anthony-Fardet.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/Anthony-Fardet-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-social\">\r\n\t\t\t\t\t\t\t<ul class=\"premium-person-social-list\">\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-facebook\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-facebook-f\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-twitter\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-twitter\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-instagram\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-instagram\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-dribbble\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-dribbble\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t<\/ul>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<h2 class=\"premium-person-name\">\r\n\t\t\t\t\t\tAnthony Fardet \t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"premium-person-title\">\r\n\t\t\t\t\t\t\t<span>\u0424\u0440\u0430\u043d\u0446\u0456\u044f<\/span>\r\n\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p>\u0434.\u043c\u0435\u0434.\u043d., \u041d\u0430\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u043d\u0430\u0443\u043a\u043e\u0432\u043e\u0433\u043e \u0406\u043d\u0441\u0442\u0438\u0442\u0443\u0442\u0443 \u0410\u0433\u0440\u043e\u043a\u0443\u043b\u044c\u0442\u0443\u0440\u0438 \u0442\u0430 \u0437\u0434\u043e\u0440\u043e\u0432\u043e\u0433\u043e \u0445\u0430\u0440\u0447\u0443\u0432\u0430\u043d\u043d\u044f INRAE<\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3aea889\" data-id=\"3aea889\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e67e30d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e67e30d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-edbf0dd\" data-id=\"edbf0dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f04837f elementor-widget elementor-widget-premium-addon-person\" data-id=\"f04837f\" data-element_type=\"widget\" data-widget_type=\"premium-addon-person.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"premium-persons-container premium-person-style2\">\r\n\t\t\t\t\t\t<div class=\"premium-person-container premium-person-none-effect\">\r\n\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/Tiziano-Barbui.jpg\" class=\"attachment-full size-full wp-image-624\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/Tiziano-Barbui.jpg 447w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/elementor\/thumbs\/Tiziano-Barbui-qign2i68tmuigbp92utzhczyvcryzihmy75mdau46w.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/Tiziano-Barbui-150x150.jpg 150w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/01\/elementor\/thumbs\/Tiziano-Barbui-qign2i67ls22ubjinxytda5lu0kcbr9x2ekg7wcw5s.jpg 200w\" sizes=\"auto, (max-width: 447px) 100vw, 447px\" \/>\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-social\">\r\n\t\t\t\t\t\t\t<ul class=\"premium-person-social-list\">\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-facebook\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-facebook-f\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-twitter\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-twitter\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-instagram\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-instagram\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-dribbble\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-dribbble\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t<\/ul>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<h2 class=\"premium-person-name\">\r\n\t\t\t\t\t\tTiziano Barbui \t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"premium-person-title\">\r\n\t\t\t\t\t\t\t<span>\u0406\u0442\u0430\u043b\u0456\u044f<\/span>\r\n\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p>\u043f\u0440\u043e\u0444\u0435\u0441\u043e\u0440 \u0433\u0435\u043c\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u0457 \u0442\u0430 \u0437\u0430\u0441\u043d\u043e\u0432\u043d\u0438\u043a \u0432\u0456\u0434\u0434\u0456\u043b\u0435\u043d\u043d\u044f \u0433\u0435\u043c\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u0457 \u0432 \u043b\u0456\u043a\u0430\u0440\u043d\u0456 \u0411\u0435\u0440\u0433\u0430\u043c\u043e, \u043d\u0430\u0443\u043a\u043e\u0432\u0438\u0439 \u0434\u0438\u0440\u0435\u043a\u0442\u043e\u0440 \u0424\u043e\u043d\u0434\u0443 \u043a\u043b\u0456\u043d\u0456\u0447\u043d\u0438\u0445 \u0434\u043e\u0441\u043b\u0456\u0434\u0436\u0435\u043d\u044c (FROM) \u0443 \u043b\u0456\u043a\u0430\u0440\u043d\u0456 Papa Giovanni XXIII<\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c3fd688\" data-id=\"c3fd688\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab95581 elementor-widget elementor-widget-premium-addon-person\" data-id=\"ab95581\" data-element_type=\"widget\" data-widget_type=\"premium-addon-person.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"premium-persons-container premium-person-style2\">\r\n\t\t\t\t\t\t<div class=\"premium-person-container premium-person-none-effect\">\r\n\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Andre-LABBE\u200b.jpg\" class=\"attachment-full size-full wp-image-403\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Andre-LABBE\u200b.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Andre-LABBE\u200b-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-social\">\r\n\t\t\t\t\t\t\t<ul class=\"premium-person-social-list\">\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-facebook\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-facebook-f\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-twitter\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-twitter\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-instagram\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-instagram\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-dribbble\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-dribbble\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t<\/ul>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<h2 class=\"premium-person-name\">\r\n\t\t\t\t\t\tAndre Labb\u00e9\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"premium-person-title\">\r\n\t\t\t\t\t\t\t<span>\u0424\u0440\u0430\u043d\u0446\u0456\u044f<\/span>\r\n\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p>\u0437\u0430\u0441\u043b\u0443\u0436\u0435\u043d\u0438\u0439 \u043f\u0440\u043e\u0444\u0435\u0441\u043e\u0440 \u0444\u0430\u043a\u0443\u043b\u044c\u0442\u0435\u0442\u0443 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 \u0442\u0430 \u043f\u0430\u0440\u0430\u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0445 \u043f\u0440\u043e\u0444\u0435\u0441\u0456\u0439 \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442\u0443 \u041a\u043b\u0435\u0440\u043c\u043e\u043d-\u041e\u0432\u0435\u0440\u043d\u044c, \u043a\u043e\u043b\u0438\u0448\u043d\u0456\u0439 \u043a\u0435\u0440\u0456\u0432\u043d\u0438\u043a \u0432\u0456\u0434\u0434\u0456\u043b\u0435\u043d\u043d\u044f \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457 \u041a\u043b\u0435\u0440\u043c\u043e\u043d-\u0424\u0435\u0440\u0440\u0430\u043d<\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-899ac12\" data-id=\"899ac12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c94eb34 elementor-widget elementor-widget-premium-addon-person\" data-id=\"c94eb34\" data-element_type=\"widget\" data-widget_type=\"premium-addon-person.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"premium-persons-container premium-person-style2\">\r\n\t\t\t\t\t\t<div class=\"premium-person-container premium-person-none-effect\">\r\n\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/08\/Artur-Mazur.jpg\" class=\"attachment-full size-full wp-image-692\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/08\/Artur-Mazur.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2024\/08\/Artur-Mazur-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-social\">\r\n\t\t\t\t\t\t\t<ul class=\"premium-person-social-list\">\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-facebook\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-facebook-f\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-twitter\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-twitter\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-instagram\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-instagram\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon premium-person-list-item premium-person-dribbble\">\r\n\t\t\t\t\t<a href=\"#\" target=\"_blank\">\r\n\t\t\t\t\t\t<i class=\"fa fa-dribbble\"><\/i>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/li>\r\n\t\t\t\t<\/ul>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<h2 class=\"premium-person-name\">\r\n\t\t\t\t\t\tArtur Mazur\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"premium-person-title\">\r\n\t\t\t\t\t\t\t<span>\u041f\u043e\u043b\u044c\u0449\u0430<\/span>\r\n\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p>\u043f\u0440\u043e\u0444\u0435\u0441\u043e\u0440, \u0434\u0435\u043a\u0430\u043d \u043c\u0435\u0434\u0438\u0447\u043d\u043e\u0433\u043e \u0444\u0430\u043a\u0443\u043b\u044c\u0442\u0435\u0442\u0443 \u0416\u0435\u0448\u0443\u0432\u0441\u044c\u043a\u043e\u0433\u043e \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442\u0443<\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f8fa11 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f8fa11\" data-element_type=\"section\" id=\"program\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9765353\" data-id=\"9765353\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73ad8fb text-center elementor-widget elementor-widget-advanced-text-block\" data-id=\"73ad8fb\" data-element_type=\"widget\" data-widget_type=\"advanced-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"futurio_extra_adv_text_block \" ><h2 class=\"text-content-block\"><p>\u0406\u043d\u043e\u0437\u0435\u043c\u043d\u0456 \u0435\u043a\u0441\u043f\u0435\u0440\u0442\u0438<\/p><\/div><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-737a81e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"737a81e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-822b7ab elementor-invisible\" data-id=\"822b7ab\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0630c38 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"0630c38\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Andre-LABBE\u200b.jpg\" class=\"attachment-full size-full wp-image-403\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Andre-LABBE\u200b.jpg 300w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/02\/Andre-LABBE\u200b-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Pr. Labbe Andre<\/h3><p class=\"elementor-image-box-description\">\u0437\u0430\u0441\u043b\u0443\u0436\u0435\u043d\u0438\u0439 \u043f\u0440\u043e\u0444\u0435\u0441\u043e\u0440 \u0444\u0430\u043a\u0443\u043b\u044c\u0442\u0435\u0442\u0443 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 \u0442\u0430 \u043f\u0430\u0440\u0430\u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0445 \u043f\u0440\u043e\u0444\u0435\u0441\u0456\u0439 \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442\u0443 \u041a\u043b\u0435\u0440\u043c\u043e\u043d-\u041e\u0432\u0435\u0440\u043d\u044c, \u043a\u0435\u0440\u0456\u0432\u043d\u0438\u043a \u0432\u0456\u0434\u0434\u0456\u043b\u0435\u043d\u043d\u044f \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457 \u041a\u043b\u0435\u0440\u043c\u043e\u043d-\u0424\u0435\u0440\u0440\u0430\u043d (\u0424\u0440\u0430\u043d\u0446\u0456\u044f)<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a3114d0 elementor-invisible\" data-id=\"a3114d0\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-055cbab elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"055cbab\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/elementor\/thumbs\/Tiziano-Barbui-qign2i68tmuigbp92utzhczyvcryzihmy75mdau46w.jpg\" title=\"Tiziano Barbui.\" alt=\"Tiziano Barbui.\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Pr. Tiziano Barbui<\/h3><p class=\"elementor-image-box-description\">\u0434.\u043c\u0435\u0434.\u043d., \u043f\u0440\u043e\u0444\u0435\u0441\u043e\u0440 \u0432\u0456\u0434\u0434\u0456\u043b\u0443 \u0433\u0435\u043c\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u0457 \n\u0442\u0430 \u043d\u0430\u0443\u043a\u043e\u0432\u0438\u0439 \u0434\u0438\u0440\u0435\u043a\u0442\u043e\u0440 RESEARCH FOUNDATION, \u043b\u0456\u043a\u0430\u0440\u043d\u044f \u041f\u0430\u043f\u0438 \u0414\u0436\u043e\u0432\u0430\u043d\u043d\u0456 XXIII (\u0406\u0442\u0430\u043b\u0456\u044f)<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0315316 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0315316\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6291701\" data-id=\"6291701\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c436a1 text-center elementor-widget elementor-widget-advanced-text-block\" data-id=\"6c436a1\" data-element_type=\"widget\" data-widget_type=\"advanced-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"futurio_extra_adv_text_block \" ><h2 class=\"text-content-block\"><p>\u041f\u0440\u043e\u0433\u0440\u0430\u043c\u0430<\/p><\/div><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e1bf6a elementor-widget elementor-widget-text-editor\" data-id=\"5e1bf6a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u041d\u0430\u0443\u043a\u043e\u0432\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u0457 \u043d\u0430\u043f\u043e\u0432\u043d\u044e\u0454\u0442\u044c\u0441\u044f \u0442\u0430 \u043c\u043e\u0436\u0435 \u0437\u043c\u0456\u043d\u044e\u0432\u0430\u0442\u0438\u0441\u044f.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9601ab4 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"9601ab4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/drive.google.com\/drive\/folders\/1YBZJjPZnDdvY44rRT8wI7fPX1srvsVC3\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0417\u0430\u0432\u0430\u043d\u0442\u0430\u0436\u0438\u0442\u0438 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0443<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba4f2f1 elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba4f2f1\" data-element_type=\"section\" id=\"registration\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8bc0d36\" data-id=\"8bc0d36\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ae55cb text-center elementor-widget elementor-widget-advanced-text-block\" data-id=\"6ae55cb\" data-element_type=\"widget\" data-widget_type=\"advanced-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"futurio_extra_adv_text_block \" ><h2 class=\"text-content-block\"><p>\u0420\u0435\u0454\u0441\u0442\u0440\u0430\u0446\u0456\u044f<\/p><\/div><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a9eb4f elementor-widget elementor-widget-html\" data-id=\"9a9eb4f\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<iframe loading=\"lazy\" id=\"reg_frame\" src=\"\" width=\"100%\" height=\"1250px\">no_iframe<\/iframe> \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0916a3f elementor-widget elementor-widget-text-editor\" data-id=\"0916a3f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"qodef-m-content\"><p class=\"qodef-m-title\">\u042f\u043a\u0449\u043e \u043d\u0430 \u0412\u0430\u0448\u043e\u043c\u0443 \u043f\u0440\u0438\u0441\u0442\u0440\u043e\u0457 \u043d\u0435 \u0432\u0456\u0434\u043e\u0431\u0440\u0430\u0436\u0443\u0454\u0442\u044c\u0441\u044f \u0444\u043e\u0440\u043c\u0430, \u043d\u0430\u0442\u0438\u0441\u043d\u0456\u0442\u044c \u043a\u043d\u043e\u043f\u043a\u0443<\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0f3824 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"b0f3824\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/video.e-registration.com.ua\/viewers\/new?event=9772292\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\" id=\"open_form_button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0412\u0406\u0414\u041a\u0420\u0418\u0422\u0418 \u0424\u041e\u0420\u041c\u0423<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebbf78a elementor-widget elementor-widget-html\" data-id=\"ebbf78a\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<script >\r\n    event = \"https:\/\/video.e-registration.com.ua\/viewers\/new?event=4973513\" \r\n    params = document.location.href.split('?')[1];\r\n    if (params == undefined) {params = 'utm_source=site'}\r\n    loc = event + \"&\" + params;\r\n    document.querySelector('#reg_frame').src = loc;\r\n    document.querySelector('#open_form_button').href = loc;\r\n\r\n<\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-729ed94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"729ed94\" data-element_type=\"section\" id=\"contacts\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-86d08d1\" data-id=\"86d08d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2275e0 text-center elementor-widget elementor-widget-advanced-text-block\" data-id=\"d2275e0\" data-element_type=\"widget\" data-widget_type=\"advanced-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"futurio_extra_adv_text_block \" ><h2 class=\"text-content-block\"><p>\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u0438<\/p><\/div><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-252b5ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"252b5ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-eb62187\" data-id=\"eb62187\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5f899d elementor-widget elementor-widget-text-editor\" data-id=\"e5f899d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h4>\u043f\u0456\u0434\u0442\u0440\u0438\u043c\u043a\u0430 \u0443\u0447\u0430\u0441\u043d\u0438\u043a\u0456\u0432 \u0442\u0456\u043b\u044c\u043a\u0438 \u0442\u0435\u043a\u0441\u0442\u043e\u0432\u0438\u043c\u0438 \u043f\u043e\u0432\u0456\u0434\u043e\u043c\u043b\u0435\u043d\u043d\u044f\u043c\u0438<\/h4>\n<h3>Viber\/Telegram: +380988591077<\/h2>\n<h3>E-mail: support@mam.net.ua<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f17535b\" data-id=\"f17535b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dffc42e elementor-widget elementor-widget-image\" data-id=\"dffc42e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/mam-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/mam-150x150.png 150w, https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/mam.png 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42b9477 elementor-widget elementor-widget-heading\" data-id=\"42b9477\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0413\u041e \u00ab\u041c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u0430 \u0430\u0441\u043e\u0446\u0456\u0430\u0446\u0456\u044f \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438\u00bb<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Menu Close \u041e\u0440\u0433\u0430\u043d\u0456\u0437\u0430\u0442\u043e\u0440\u0438 \u0415\u043a\u0441\u043f\u0435\u0440\u0442\u0438 \u041f\u0440\u043e\u0433\u0440\u0430\u043c\u0430 \u0420\u0435\u0454\u0441\u0442\u0440\u0430\u0446\u0456\u044f \u041a\u043e\u043d\u0442\u0430\u043a\u0442\u0438 \u041c\u043e\u0432\u0438 \u041e\u0440\u0433\u0430\u043d\u0456\u0437\u0430\u0442\u043e\u0440\u0438 \u0415\u043a\u0441\u043f\u0435\u0440\u0442\u0438 \u041f\u0440\u043e\u0433\u0440\u0430\u043c\u0430 \u0420\u0435\u0454\u0441\u0442\u0440\u0430\u0446\u0456\u044f \u041a\u043e\u043d\u0442\u0430\u043a\u0442\u0438 \u041c\u043e\u0432\u0438 \u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0425VI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457 27 \u043b\u044e\u0442\u043e\u0433\u043e &#8211; 2 \u0431\u0435\u0440\u0435\u0437\u043d\u044f 2025 \u0440\u043e\u043a\u0443 \u0420\u0415\u0404\u0421\u0422\u0420\u0410\u0426\u0406\u042f \u041f\u0420\u041e\u0413\u0420\u0410\u041c\u0410 \u041e\u043d\u043b\u0430\u0439\u043d \u0442\u0440\u0430\u043d\u0441\u043b\u044f\u0446\u0456\u044f \u0422\u0440\u0430\u043d\u0441\u043b\u044f\u0446\u0456\u044f \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u0457 online, \u0437 \u043c\u043e\u0436\u043b\u0438\u0432\u0456\u0441\u0442\u044e \u043f\u043e\u0432\u0442\u043e\u0440\u043d\u043e\u0433\u043e \u043f\u0435\u0440\u0435\u0433\u043b\u044f\u0434\u0443 \u0443 \u0437\u0430\u043f\u0438\u0441\u0456 \u041c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u0456 \u0435\u043a\u0441\u043f\u0435\u0440\u0442\u0438 \u0414\u043e\u0441\u0432\u0456\u0434\u043e\u043c \u0434\u0456\u043b\u044f\u0442\u044c\u0441\u044f \u043f\u0440\u043e\u0432\u0456\u0434\u043d\u0456 \u0441\u043f\u0435\u0446\u0456\u0430\u043b\u0456\u0441\u0442\u0438 \u0437 \u0423\u043a\u0440\u0430\u0457\u043d\u0438, \u043a\u0440\u0430\u0457\u043d \u0404\u0421 \u0442\u0430 \u0421\u0428\u0410 \u041d\u0430\u0441\u0438\u0447\u0435\u043d\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0430 \u041d\u0430&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-714","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457<\/title>\n<meta name=\"description\" content=\"\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0434\u043b\u044f \u043b\u0456\u043a\u0430\u0440\u0456\u0432 &quot;XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457&quot;, 27 \u043b\u044e\u0442\u043e\u0433\u043e - 2 \u0431\u0435\u0440\u0435\u0437\u043d\u044f 2025 \u0440\u043e\u043a\u0443, \u043e\u0444\u043b\u0430\u0439\u043d + \u043e\u043d\u043b\u0430\u0439\u043d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mam.net.ua\/pediatrics\/xvi\/\" \/>\n<meta property=\"og:locale\" content=\"uk_UA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457\" \/>\n<meta property=\"og:description\" content=\"\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0434\u043b\u044f \u043b\u0456\u043a\u0430\u0440\u0456\u0432 &quot;XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457&quot;, 27 \u043b\u044e\u0442\u043e\u0433\u043e - 2 \u0431\u0435\u0440\u0435\u0437\u043d\u044f 2025 \u0440\u043e\u043a\u0443, \u043e\u0444\u043b\u0430\u0439\u043d + \u043e\u043d\u043b\u0430\u0439\u043d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mam.net.ua\/pediatrics\/xvi\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0428\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-22T11:27:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/Beketova.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u0431\u043b. \u0447\u0430\u0441 \u0447\u0438\u0442\u0430\u043d\u043d\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 \u0445\u0432\u0438\u043b\u0438\u043d\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mam.net.ua\/pediatrics\/xvi\/\",\"url\":\"https:\/\/mam.net.ua\/pediatrics\/xvi\/\",\"name\":\"XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457\",\"isPartOf\":{\"@id\":\"https:\/\/mam.net.ua\/pediatrics\/#website\"},\"datePublished\":\"2025-01-19T23:46:43+00:00\",\"dateModified\":\"2025-02-22T11:27:50+00:00\",\"description\":\"\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0434\u043b\u044f \u043b\u0456\u043a\u0430\u0440\u0456\u0432 \\\"XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457\\\", 27 \u043b\u044e\u0442\u043e\u0433\u043e - 2 \u0431\u0435\u0440\u0435\u0437\u043d\u044f 2025 \u0440\u043e\u043a\u0443, \u043e\u0444\u043b\u0430\u0439\u043d + \u043e\u043d\u043b\u0430\u0439\u043d\",\"breadcrumb\":{\"@id\":\"https:\/\/mam.net.ua\/pediatrics\/xvi\/#breadcrumb\"},\"inLanguage\":\"uk\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mam.net.ua\/pediatrics\/xvi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mam.net.ua\/pediatrics\/xvi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043e\u043b\u043e\u0432\u043d\u0430\",\"item\":\"https:\/\/mam.net.ua\/pediatrics\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mam.net.ua\/pediatrics\/#website\",\"url\":\"https:\/\/mam.net.ua\/pediatrics\/\",\"name\":\"\u0428\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/mam.net.ua\/pediatrics\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mam.net.ua\/pediatrics\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"uk\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mam.net.ua\/pediatrics\/#organization\",\"name\":\"\u0428\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457\",\"url\":\"https:\/\/mam.net.ua\/pediatrics\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"uk\",\"@id\":\"https:\/\/mam.net.ua\/pediatrics\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/logo.png\",\"contentUrl\":\"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/logo.png\",\"width\":75,\"height\":80,\"caption\":\"\u0428\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457\"},\"image\":{\"@id\":\"https:\/\/mam.net.ua\/pediatrics\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457","description":"\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0434\u043b\u044f \u043b\u0456\u043a\u0430\u0440\u0456\u0432 \"XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457\", 27 \u043b\u044e\u0442\u043e\u0433\u043e - 2 \u0431\u0435\u0440\u0435\u0437\u043d\u044f 2025 \u0440\u043e\u043a\u0443, \u043e\u0444\u043b\u0430\u0439\u043d + \u043e\u043d\u043b\u0430\u0439\u043d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mam.net.ua\/pediatrics\/xvi\/","og_locale":"uk_UA","og_type":"article","og_title":"XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457","og_description":"\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0434\u043b\u044f \u043b\u0456\u043a\u0430\u0440\u0456\u0432 \"XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457\", 27 \u043b\u044e\u0442\u043e\u0433\u043e - 2 \u0431\u0435\u0440\u0435\u0437\u043d\u044f 2025 \u0440\u043e\u043a\u0443, \u043e\u0444\u043b\u0430\u0439\u043d + \u043e\u043d\u043b\u0430\u0439\u043d","og_url":"https:\/\/mam.net.ua\/pediatrics\/xvi\/","og_site_name":"\u0428\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457","article_modified_time":"2025-02-22T11:27:50+00:00","og_image":[{"url":"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/Beketova.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u0431\u043b. \u0447\u0430\u0441 \u0447\u0438\u0442\u0430\u043d\u043d\u044f":"8 \u0445\u0432\u0438\u043b\u0438\u043d"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mam.net.ua\/pediatrics\/xvi\/","url":"https:\/\/mam.net.ua\/pediatrics\/xvi\/","name":"XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457","isPartOf":{"@id":"https:\/\/mam.net.ua\/pediatrics\/#website"},"datePublished":"2025-01-19T23:46:43+00:00","dateModified":"2025-02-22T11:27:50+00:00","description":"\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0434\u043b\u044f \u043b\u0456\u043a\u0430\u0440\u0456\u0432 \"XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457\", 27 \u043b\u044e\u0442\u043e\u0433\u043e - 2 \u0431\u0435\u0440\u0435\u0437\u043d\u044f 2025 \u0440\u043e\u043a\u0443, \u043e\u0444\u043b\u0430\u0439\u043d + \u043e\u043d\u043b\u0430\u0439\u043d","breadcrumb":{"@id":"https:\/\/mam.net.ua\/pediatrics\/xvi\/#breadcrumb"},"inLanguage":"uk","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mam.net.ua\/pediatrics\/xvi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mam.net.ua\/pediatrics\/xvi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043e\u043b\u043e\u0432\u043d\u0430","item":"https:\/\/mam.net.ua\/pediatrics\/"},{"@type":"ListItem","position":2,"name":"XVI \u0410\u043a\u0430\u0434\u0435\u043c\u0456\u0447\u043d\u0430 \u0448\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457"}]},{"@type":"WebSite","@id":"https:\/\/mam.net.ua\/pediatrics\/#website","url":"https:\/\/mam.net.ua\/pediatrics\/","name":"\u0428\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457","description":"","publisher":{"@id":"https:\/\/mam.net.ua\/pediatrics\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mam.net.ua\/pediatrics\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"uk"},{"@type":"Organization","@id":"https:\/\/mam.net.ua\/pediatrics\/#organization","name":"\u0428\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457","url":"https:\/\/mam.net.ua\/pediatrics\/","logo":{"@type":"ImageObject","inLanguage":"uk","@id":"https:\/\/mam.net.ua\/pediatrics\/#\/schema\/logo\/image\/","url":"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/logo.png","contentUrl":"https:\/\/mam.net.ua\/pediatrics\/wp-content\/uploads\/2023\/01\/logo.png","width":75,"height":80,"caption":"\u0428\u043a\u043e\u043b\u0430 \u0437 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457"},"image":{"@id":"https:\/\/mam.net.ua\/pediatrics\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mam.net.ua\/pediatrics\/wp-json\/wp\/v2\/pages\/714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mam.net.ua\/pediatrics\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mam.net.ua\/pediatrics\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mam.net.ua\/pediatrics\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mam.net.ua\/pediatrics\/wp-json\/wp\/v2\/comments?post=714"}],"version-history":[{"count":31,"href":"https:\/\/mam.net.ua\/pediatrics\/wp-json\/wp\/v2\/pages\/714\/revisions"}],"predecessor-version":[{"id":752,"href":"https:\/\/mam.net.ua\/pediatrics\/wp-json\/wp\/v2\/pages\/714\/revisions\/752"}],"wp:attachment":[{"href":"https:\/\/mam.net.ua\/pediatrics\/wp-json\/wp\/v2\/media?parent=714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}