{"id":1928,"date":"2025-03-17T23:12:58","date_gmt":"2025-03-17T21:12:58","guid":{"rendered":"https:\/\/mam.net.ua\/paim\/?page_id=1928"},"modified":"2025-04-18T11:46:35","modified_gmt":"2025-04-18T08:46:35","slug":"conference2025","status":"publish","type":"page","link":"https:\/\/mam.net.ua\/paim\/conference2025\/","title":{"rendered":"\u041f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 &#8211; 2025"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1928\" class=\"elementor elementor-1928\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c40c5b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9c40c5b\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d113b45\" data-id=\"d113b45\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7090c1 elementor-widget elementor-widget-image\" data-id=\"b7090c1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.3 - 07-03-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/04\/2025.04.23.-MAM-PAIM-banner-final-1024x576.jpg\" class=\"attachment-large size-large wp-image-1945\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/04\/2025.04.23.-MAM-PAIM-banner-final-1024x576.jpg 1024w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/04\/2025.04.23.-MAM-PAIM-banner-final-300x169.jpg 300w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/04\/2025.04.23.-MAM-PAIM-banner-final-768x432.jpg 768w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/04\/2025.04.23.-MAM-PAIM-banner-final-1536x864.jpg 1536w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/04\/2025.04.23.-MAM-PAIM-banner-final-1000x563.jpg 1000w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/04\/2025.04.23.-MAM-PAIM-banner-final-230x129.jpg 230w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/04\/2025.04.23.-MAM-PAIM-banner-final-350x197.jpg 350w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/04\/2025.04.23.-MAM-PAIM-banner-final-480x270.jpg 480w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/04\/2025.04.23.-MAM-PAIM-banner-final.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f816b85 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f816b85\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-861bb0e\" data-id=\"861bb0e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cff588 elementor-widget elementor-widget-text-editor\" data-id=\"3cff588\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.3 - 07-03-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0437 \u043c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u044e \u0443\u0447\u0430\u0441\u0442\u044e<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b30aa21 elementor-widget elementor-widget-heading\" data-id=\"b30aa21\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.3 - 07-03-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">\u041f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \n\u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07b1011 elementor-widget elementor-widget-text-editor\" data-id=\"07b1011\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>23-24 \u043a\u0432\u0456\u0442\u043d\u044f <\/strong><strong>2025 <\/strong><strong>\u0440\u043e\u043a\u0443 | <\/strong><strong>\u041e\u043d\u043b\u0430\u0439\u043d<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48f4e5f elementor-align-center elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"48f4e5f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"#registration\" class=\"elementor-button-link elementor-button elementor-size-xl elementor-animation-grow\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0417\u0410\u0420\u0415\u0404\u0421\u0422\u0420\u0423\u0412\u0410\u0422\u0418\u0421\u042f<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad4b455 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ad4b455\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e593d1\" data-id=\"6e593d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05197fc elementor-widget elementor-widget-ha-gradient-heading happy-addon ha-gradient-heading\" data-id=\"05197fc\" data-element_type=\"widget\" data-widget_type=\"ha-gradient-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"ha-gradient-heading\">\u041e\u0420\u0413\u0410\u041d\u0406\u0417\u0410\u0422\u041e\u0420\u0418<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-58b4ec2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58b4ec2\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-8208be4 elementor-invisible\" data-id=\"8208be4\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a4749d elementor-widget elementor-widget-image\" data-id=\"8a4749d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/\u0423\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442-\u041d\u044f\u043d\u044c\u043a\u043e\u0432\u0441\u044c\u043a\u0438\u0445.png\" class=\"attachment-large size-large wp-image-1851\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/\u0423\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442-\u041d\u044f\u043d\u044c\u043a\u043e\u0432\u0441\u044c\u043a\u0438\u0445.png 300w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/\u0423\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442-\u041d\u044f\u043d\u044c\u043a\u043e\u0432\u0441\u044c\u043a\u0438\u0445-150x150.png 150w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/\u0423\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442-\u041d\u044f\u043d\u044c\u043a\u043e\u0432\u0441\u044c\u043a\u0438\u0445-230x230.png 230w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-452a758 elementor-invisible\" data-id=\"452a758\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80dd75f elementor-widget elementor-widget-image\" data-id=\"80dd75f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/Ukraine-now.png\" class=\"attachment-large size-large wp-image-1855\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/Ukraine-now.png 300w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/Ukraine-now-150x150.png 150w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/Ukraine-now-230x230.png 230w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-272116b elementor-invisible\" data-id=\"272116b\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc21acd elementor-widget elementor-widget-image\" data-id=\"cc21acd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/Danylo-Halytsky-Lviv-National-Medical-University.png\" class=\"attachment-large size-large wp-image-1854\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/Danylo-Halytsky-Lviv-National-Medical-University.png 300w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/Danylo-Halytsky-Lviv-National-Medical-University-150x150.png 150w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/Danylo-Halytsky-Lviv-National-Medical-University-230x230.png 230w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-4576b9f elementor-invisible\" data-id=\"4576b9f\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09415aa elementor-widget elementor-widget-image\" data-id=\"09415aa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/\u0420\u0438\u0442\u043c.png\" class=\"attachment-large size-large wp-image-1853\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/\u0420\u0438\u0442\u043c.png 300w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/\u0420\u0438\u0442\u043c-150x150.png 150w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/\u0420\u0438\u0442\u043c-230x230.png 230w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-c2bd8ee elementor-invisible\" data-id=\"c2bd8ee\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f44fef1 elementor-widget elementor-widget-image\" data-id=\"f44fef1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/mam.png\" class=\"attachment-large size-large wp-image-1852\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/mam.png 300w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/mam-150x150.png 150w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/03\/mam-230x230.png 230w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cfad720 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"cfad720\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16d87de\" data-id=\"16d87de\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbb9e8c elementor-widget elementor-widget-ha-gradient-heading happy-addon ha-gradient-heading\" data-id=\"bbb9e8c\" data-element_type=\"widget\" data-widget_type=\"ha-gradient-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"ha-gradient-heading\">\u041d\u0410\u0423\u041a\u041e\u0412\u0418\u0419 \u041a\u041e\u041c\u0406\u0422\u0415\u0422<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-06a1e95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06a1e95\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ea0104a elementor-invisible\" data-id=\"ea0104a\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af656e8 ha-card--top ha-card--tablet-top ha-card--mobile-top elementor-widget elementor-widget-ha-card happy-addon ha-card\" data-id=\"af656e8\" data-element_type=\"widget\" data-widget_type=\"ha-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t\t\t<figure class=\"ha-card-figure\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"333\" height=\"450\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/1-\u041d\u044f\u043d\u044c\u043a\u043e\u0432\u0441\u044c\u043a\u0438\u0439-1.jpg\" class=\"attachment-full size-full wp-image-1746\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/1-\u041d\u044f\u043d\u044c\u043a\u043e\u0432\u0441\u044c\u043a\u0438\u0439-1.jpg 333w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/1-\u041d\u044f\u043d\u044c\u043a\u043e\u0432\u0441\u044c\u043a\u0438\u0439-1-222x300.jpg 222w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/1-\u041d\u044f\u043d\u044c\u043a\u043e\u0432\u0441\u044c\u043a\u0438\u0439-1-230x311.jpg 230w\" sizes=\"auto, (max-width: 333px) 100vw, 333px\" \/>\t\t\t\t\t\t\t<\/figure>\n\t\t\n\t\t<div class=\"ha-card-body\">\n\n\t\t\t<h2 class=\"ha-card-title\">\u041d\u042f\u041d\u042c\u041a\u041e\u0412\u0421\u042c\u041a\u0418\u0419 \u0421\u0435\u0440\u0433\u0456\u0439 \u041b\u0435\u043e\u043d\u0456\u0434\u043e\u0432\u0438\u0447<\/h2>\n\t\t\t\t\t\t\t<div class=\"ha-card-text\">\n\t\t\t\t\t<p>\u041f\u0440\u043e\u0444\u0435\u0441\u043e\u0440, \u0434\u043e\u043a\u0442\u043e\u0440 \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0445 \u043d\u0430\u0443\u043a\n\u0417\u0430\u0432\u0456\u0434\u0443\u0432\u0430\u0447 \u043a\u0430\u0444\u0435\u0434\u0440\u0438 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457 \u21161 \u041b\u044c\u0432\u0456\u0432\u0441\u044c\u043a\u043e\u0433\u043e \u043d\u0430\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u043c\u0435\u0434\u0438\u0447\u043d\u043e\u0433\u043e \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442\u0443 \u0456\u043c\u0435\u043d\u0456 \u0414\u0430\u043d\u0438\u043b\u0430 \u0413\u0430\u043b\u0438\u0446\u044c\u043a\u043e\u0433\u043e, \u00ab\u0423\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442\u0443 \u0437\u0434\u043e\u0440\u043e\u0432\u043e\u0457 \u0434\u0438\u0442\u0438\u043d\u0438 \u041d\u044f\u043d\u044c\u043a\u043e\u0432\u0441\u044c\u043a\u0438\u0445\u00bb, \u043e\u0434\u0438\u043d \u0437 \u043e\u0441\u043d\u043e\u0432\u043e\u043f\u043e\u043b\u043e\u0436\u043d\u0438\u043a\u0456\u0432 \u041b\u044c\u0432\u0456\u0432\u0441\u044c\u043a\u043e\u0457 \u0448\u043a\u043e\u043b\u0438 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-af1967d elementor-invisible\" data-id=\"af1967d\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3026ae6 ha-card--top ha-card--tablet-top ha-card--mobile-top elementor-widget elementor-widget-ha-card happy-addon ha-card\" data-id=\"3026ae6\" data-element_type=\"widget\" data-widget_type=\"ha-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t\t\t<figure class=\"ha-card-figure\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"333\" height=\"450\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/2-\u041d\u044f\u043d\u044c\u043a\u043e\u0432\u0441\u044c\u043a\u0430-1.jpg\" class=\"attachment-full size-full wp-image-1747\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/2-\u041d\u044f\u043d\u044c\u043a\u043e\u0432\u0441\u044c\u043a\u0430-1.jpg 333w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/2-\u041d\u044f\u043d\u044c\u043a\u043e\u0432\u0441\u044c\u043a\u0430-1-222x300.jpg 222w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/2-\u041d\u044f\u043d\u044c\u043a\u043e\u0432\u0441\u044c\u043a\u0430-1-230x311.jpg 230w\" sizes=\"auto, (max-width: 333px) 100vw, 333px\" \/>\t\t\t\t\t\t\t<\/figure>\n\t\t\n\t\t<div class=\"ha-card-body\">\n\n\t\t\t<h2 class=\"ha-card-title\">\u041d\u042f\u041d\u042c\u041a\u041e\u0412\u0421\u042c\u041a\u0410 \u041e\u043b\u0435\u043d\u0430 \u0421\u0435\u0440\u0433\u0456\u0457\u0432\u043d\u0430<\/h2>\n\t\t\t\t\t\t\t<div class=\"ha-card-text\">\n\t\t\t\t\t<p>\u043f\u0440\u043e\u0444\u0435\u0441\u043e\u0440, \u0434.\u043c\u0435\u0434.\u043d, \u043f\u0435\u0434\u0456\u0430\u0442\u0440, \u0434\u0438\u0442\u044f\u0447\u0438\u0439 \u0433\u0430\u0441\u0442\u0440\u043e\u0435\u043d\u0442\u0435\u0440\u043e\u043b\u043e\u0433, \u0434\u0456\u0454\u0442\u043e\u043b\u043e\u0433, \u0447\u043b\u0435\u043d \u0411\u0440\u0438\u0442\u0430\u043d\u0441\u044c\u043a\u043e\u0457 \u0434\u0456\u0454\u0442\u043e\u043b\u043e\u0433\u0456\u0447\u043d\u043e\u0457 \u0430\u0441\u043e\u0446\u0456\u0430\u0446\u0456\u0457 \u0442\u0430 ESPGHAN<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-bb1f124 elementor-invisible\" data-id=\"bb1f124\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9fd6ce2 ha-card--top ha-card--tablet-top ha-card--mobile-top elementor-widget elementor-widget-ha-card happy-addon ha-card\" data-id=\"9fd6ce2\" data-element_type=\"widget\" data-widget_type=\"ha-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t\t\t<figure class=\"ha-card-figure\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"333\" height=\"450\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/3-\u0427\u0435\u0440\u043d\u044f\u0433\u0430-1.jpg\" class=\"attachment-full size-full wp-image-1748\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/3-\u0427\u0435\u0440\u043d\u044f\u0433\u0430-1.jpg 333w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/3-\u0427\u0435\u0440\u043d\u044f\u0433\u0430-1-222x300.jpg 222w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/3-\u0427\u0435\u0440\u043d\u044f\u0433\u0430-1-230x311.jpg 230w\" sizes=\"auto, (max-width: 333px) 100vw, 333px\" \/>\t\t\t\t\t\t\t<\/figure>\n\t\t\n\t\t<div class=\"ha-card-body\">\n\n\t\t\t<h2 class=\"ha-card-title\">\u0427\u0415\u0420\u041d\u042f\u0413\u0410-\u0420\u041e\u0419\u041a\u041e \u0423\u043b\u044f\u043d\u0430 \u041f\u0435\u0442\u0440\u0456\u0432\u043d\u0430<\/h2>\n\t\t\t\t\t\t\t<div class=\"ha-card-text\">\n\t\t\t\t\t<p>\u041a\u0430\u043d\u0434\u0438\u0434\u0430\u0442 \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0445 \u043d\u0430\u0443\u043a, \u0434\u043e\u0446\u0435\u043d\u0442 \u043a\u0430\u0444\u0435\u0434\u0440\u0438 \u043f\u0440\u043e\u043c\u0435\u043d\u0435\u0432\u043e\u0457 \u0434\u0456\u0430\u0433\u043d\u043e\u0441\u0442\u0438\u043a\u0438, \u041b\u044c\u0432\u0456\u0432\u0441\u044c\u043a\u0438\u0439 \u043d\u0430\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u0438\u0439 \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0439 \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442 \u0456\u043c\u0435\u043d\u0456 \u0414\u0430\u043d\u0438\u043b\u0430 \u0413\u0430\u043b\u0438\u0446\u044c\u043a\u043e\u0433\u043e, \u0413\u043e\u043b\u043e\u0432\u0430 \u0410\u0441\u043e\u0446\u0456\u0430\u0446\u0456\u0457 \u0444\u0430\u0445\u0456\u0432\u0446\u0456\u0432 \u0441\u0435\u0440\u0446\u0435\u0432\u043e-\u0441\u0443\u0434\u0438\u043d\u043d\u043e\u0457 \u043f\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u0457<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-68c4bc9 elementor-invisible\" data-id=\"68c4bc9\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-750e930 ha-card--top ha-card--tablet-top ha-card--mobile-top elementor-widget elementor-widget-ha-card happy-addon ha-card\" data-id=\"750e930\" data-element_type=\"widget\" data-widget_type=\"ha-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t\t\t<figure class=\"ha-card-figure\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"333\" height=\"450\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/04\/\u0421\u043e\u0440\u043e\u043a\u0456\u0432\u0441\u044c\u043a\u0438\u0439-\u041c.\u0421.jpg\" class=\"attachment-full size-full wp-image-1835\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/04\/\u0421\u043e\u0440\u043e\u043a\u0456\u0432\u0441\u044c\u043a\u0438\u0439-\u041c.\u0421.jpg 333w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/04\/\u0421\u043e\u0440\u043e\u043a\u0456\u0432\u0441\u044c\u043a\u0438\u0439-\u041c.\u0421-222x300.jpg 222w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/04\/\u0421\u043e\u0440\u043e\u043a\u0456\u0432\u0441\u044c\u043a\u0438\u0439-\u041c.\u0421-230x311.jpg 230w\" sizes=\"auto, (max-width: 333px) 100vw, 333px\" \/>\t\t\t\t\t\t\t<\/figure>\n\t\t\n\t\t<div class=\"ha-card-body\">\n\n\t\t\t<h2 class=\"ha-card-title\">\u0421\u041e\u0420\u041e\u041a\u0406\u0412\u0421\u042c\u041a\u0418\u0419 \u041c\u0438\u0445\u0430\u0439\u043b\u043e \u0421\u0442\u0435\u043f\u0430\u043d\u043e\u0432\u0438\u0447<\/h2>\n\t\t\t\t\t\t\t<div class=\"ha-card-text\">\n\t\t\t\t\t<p>\u041a\u0430\u043d\u0434\u0438\u0434\u0430\u0442 \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0445 \u043d\u0430\u0443\u043a, \u0437\u0430\u0432\u0456\u0434\u0443\u0432\u0430\u0447 \u043a\u0430\u0444\u0435\u0434\u0440\u0438 \u043f\u0440\u043e\u043c\u0435\u043d\u0435\u0432\u043e\u0456\u0308 \u0434\u0456\u0430\u0433\u043d\u043e\u0441\u0442\u0438\u043a\u0438, \u041b\u044c\u0432\u0456\u0432\u0441\u044c\u043a\u0438\u0439 \u043d\u0430\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u0438\u0439 \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0439 \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442 \u0456\u043c\u0435\u043d\u0456 \u0414\u0430\u043d\u0438\u043b\u0430 \u0413\u0430\u043b\u0438\u0446\u044c\u043a\u043e\u0433\u043e<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cd7961 elementor-section-height-default elementor-section-boxed elementor-section-height-default\" data-id=\"6cd7961\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-22a24761\" data-id=\"22a24761\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11c3417f elementor-widget elementor-widget-heading\" data-id=\"11c3417f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0422\u0435\u043c\u0430\u0442\u0438\u043a\u0438<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a37f5d animated-fast elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"6a37f5d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/mam.net.ua\/paim\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0421\u0435\u043a\u0446\u0456\u044f 1: \u041a\u0430\u0440\u0434\u0456\u043e\u043b\u043e\u0433\u0456\u044f<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9eb2cb6 animated-fast elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"9eb2cb6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0421\u0435\u043a\u0446\u0456\u044f 2: \u041f\u0443\u043b\u044c\u043c\u043e\u043d\u043e\u043b\u043e\u0433\u0456\u044f<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d244af6 animated-fast elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"d244af6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0421\u0435\u043a\u0446\u0456\u044f 3: \u0413\u0430\u0441\u0442\u0440\u043e\u0435\u043d\u0442\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u044f<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8aa2bcf animated-fast elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"8aa2bcf\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0421\u0435\u043a\u0446\u0456\u044f 4: \u0415\u043d\u0434\u043e\u043a\u0440\u0438\u043d\u043e\u043b\u043e\u0433\u0456\u044f<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1dafe2 animated-fast elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"e1dafe2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0421\u0435\u043a\u0446\u0456\u044f 5: \u041f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u044f<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff3a933 animated-fast elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"ff3a933\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:800}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0421\u0435\u043a\u0446\u0456\u044f 6: \u041d\u0435\u0432\u0440\u043e\u043b\u043e\u0433\u0456\u044f<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-738af180\" data-id=\"738af180\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f3cb95f elementor-widget elementor-widget-image\" data-id=\"4f3cb95f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"868\" height=\"573\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/specials_en.png\" class=\"attachment-large size-large wp-image-1740\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/specials_en.png 868w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/specials_en-300x198.png 300w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/specials_en-768x507.png 768w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/specials_en-230x152.png 230w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/specials_en-350x231.png 350w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/specials_en-480x317.png 480w\" sizes=\"auto, (max-width: 868px) 100vw, 868px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a7e9a48 elementor-section-height-default elementor-section-boxed elementor-section-height-default\" data-id=\"a7e9a48\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d438bc1\" data-id=\"d438bc1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ce68b9 elementor-widget elementor-widget-heading\" data-id=\"2ce68b9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u041d\u0430 \u0412\u0430\u0441 \u043e\u0447\u0456\u043a\u0443\u0454\u200b<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3637f49 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3637f49\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7bd92e7\" data-id=\"7bd92e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f49c779 elementor-widget elementor-widget-ha-flip-box happy-addon ha-flip-box\" data-id=\"f49c779\" data-element_type=\"widget\" data-widget_type=\"ha-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"ha-flip-box-container ha-flip-effect-classic\">\n\n            <div class=\"ha-flip-box-inner ha-flip-right\">\n                <div class=\"ha-flip-box-inner-wrapper\">\n                    <div class=\"ha-flip-box-front\">\n                        <div class=\"ha-flip-box-front-inner\">\n                            <div class=\"icon-wrap\">\n                                                                    <span class=\"ha-flip-icon icon\">\n                                        <i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>                                    <\/span>\n                                                                                            <\/div>\n\n                            <div class=\"ha-text\">\n                                                                    <h2 class=\"ha-flip-box-heading\">\u043b\u0435\u043a\u0446\u0456\u0457 \u0437 \u043e\u0441\u043d\u043e\u0432\u043d\u0438\u0445 \u043d\u0430\u043f\u0440\u044f\u043c\u043a\u0456\u0432 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u0457<\/h2>\n                                \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"ha-flip-box-back\">\n                        <div class=\"ha-flip-box-back-inner\">\n                            <div class=\"icon-wrap\">\n                                                                                            <\/div>\n\n                            <div class=\"ha-text\">\n                                                                    <h2 class=\"ha-flip-box-heading-back\">\u043b\u0435\u043a\u0446\u0456\u0457 \u0437 \u043e\u0441\u043d\u043e\u0432\u043d\u0438\u0445 \u043d\u0430\u043f\u0440\u044f\u043c\u043a\u0456\u0432 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u0457<\/h2>\n                                \n                                                                    <p class=\"ha-desc\">\u041f\u0435\u0440\u0435\u0433\u043b\u044f\u0434\u0430\u0439\u0442\u0435 \u0442\u0440\u0430\u043d\u0441\u043b\u044f\u0446\u0456\u044e \u043b\u0435\u043a\u0446\u0456\u0439 \u043e\u043d\u043b\u0430\u0439\u043d \u0442\u0430 \u0432 \u0437\u0430\u043f\u0438\u0441\u0456<\/p>\n                                                            <\/div>\n\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b6b4a7 elementor-widget elementor-widget-ha-flip-box happy-addon ha-flip-box\" data-id=\"0b6b4a7\" data-element_type=\"widget\" data-widget_type=\"ha-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"ha-flip-box-container ha-flip-effect-classic\">\n\n            <div class=\"ha-flip-box-inner ha-flip-right\">\n                <div class=\"ha-flip-box-inner-wrapper\">\n                    <div class=\"ha-flip-box-front\">\n                        <div class=\"ha-flip-box-front-inner\">\n                            <div class=\"icon-wrap\">\n                                                                    <span class=\"ha-flip-icon icon\">\n                                        <i aria-hidden=\"true\" class=\"hm hm-testimonial\"><\/i>                                    <\/span>\n                                                                                            <\/div>\n\n                            <div class=\"ha-text\">\n                                                                    <h2 class=\"ha-flip-box-heading\">\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u043e\u0431\u0433\u043e\u0432\u043e\u0440\u0435\u043d\u043d\u044f<\/h2>\n                                \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"ha-flip-box-back\">\n                        <div class=\"ha-flip-box-back-inner\">\n                            <div class=\"icon-wrap\">\n                                                                                            <\/div>\n\n                            <div class=\"ha-text\">\n                                                                    <h2 class=\"ha-flip-box-heading-back\">\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u043e\u0431\u0433\u043e\u0432\u043e\u0440\u0435\u043d\u043d\u044f<\/h2>\n                                \n                                                                    <p class=\"ha-desc\">\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0440\u0435\u043a\u043e\u043c\u0435\u043d\u0434\u0430\u0446\u0456\u0457 \u0432\u0456\u0434 \u043f\u0440\u043e\u0432\u0456\u0434\u043d\u0438\u0445 \u0435\u043a\u0441\u043f\u0435\u0440\u0442\u0456\u0432 <\/p>\n                                                            <\/div>\n\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e045eb7\" data-id=\"e045eb7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa88be3 elementor-widget elementor-widget-ha-flip-box happy-addon ha-flip-box\" data-id=\"aa88be3\" data-element_type=\"widget\" data-widget_type=\"ha-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"ha-flip-box-container ha-flip-effect-classic\">\n\n            <div class=\"ha-flip-box-inner ha-flip-right\">\n                <div class=\"ha-flip-box-inner-wrapper\">\n                    <div class=\"ha-flip-box-front\">\n                        <div class=\"ha-flip-box-front-inner\">\n                            <div class=\"icon-wrap\">\n                                                                    <span class=\"ha-flip-icon icon\">\n                                        <i aria-hidden=\"true\" class=\"hm hm-speaker\"><\/i>                                    <\/span>\n                                                                                            <\/div>\n\n                            <div class=\"ha-text\">\n                                                                    <h2 class=\"ha-flip-box-heading\">\u0440\u043e\u0437\u0431\u043e\u0440\u0438 \u043a\u043b\u0456\u043d\u0456\u0447\u043d\u0438\u0445 \u0432\u0438\u043f\u0430\u0434\u043a\u0456\u0432 \u0437 \u0435\u043a\u0441\u043f\u0435\u0440\u0442\u0430\u043c\u0438<\/h2>\n                                \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"ha-flip-box-back\">\n                        <div class=\"ha-flip-box-back-inner\">\n                            <div class=\"icon-wrap\">\n                                                                                            <\/div>\n\n                            <div class=\"ha-text\">\n                                                                    <h2 class=\"ha-flip-box-heading-back\">\u0440\u043e\u0437\u0431\u043e\u0440\u0438 \u043a\u043b\u0456\u043d\u0456\u0447\u043d\u0438\u0445 \u0432\u0438\u043f\u0430\u0434\u043a\u0456\u0432 \u0437 \u0435\u043a\u0441\u043f\u0435\u0440\u0442\u0430\u043c\u0438<\/h2>\n                                \n                                                                    <p class=\"ha-desc\">\u0434\u0438\u0441\u043a\u0443\u0441\u0456\u0457 \u0442\u0430 \u043e\u0433\u043b\u044f\u0434 \u043a\u043b\u0456\u043d\u0456\u0447\u043d\u0438\u0445 \u0432\u0438\u043f\u0430\u0434\u043a\u0456\u0432<\/p>\n                                                            <\/div>\n\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ace065c elementor-widget elementor-widget-ha-flip-box happy-addon ha-flip-box\" data-id=\"ace065c\" data-element_type=\"widget\" data-widget_type=\"ha-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"ha-flip-box-container ha-flip-effect-classic\">\n\n            <div class=\"ha-flip-box-inner ha-flip-right\">\n                <div class=\"ha-flip-box-inner-wrapper\">\n                    <div class=\"ha-flip-box-front\">\n                        <div class=\"ha-flip-box-front-inner\">\n                            <div class=\"icon-wrap\">\n                                                                    <span class=\"ha-flip-icon icon\">\n                                        <i aria-hidden=\"true\" class=\"fas fa-globe-europe\"><\/i>                                    <\/span>\n                                                                                            <\/div>\n\n                            <div class=\"ha-text\">\n                                                                    <h2 class=\"ha-flip-box-heading\">\u0456\u043d\u043e\u0437\u0435\u043c\u043d\u0456 \u0441\u043f\u0456\u043a\u0435\u0440\u0438<\/h2>\n                                \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"ha-flip-box-back\">\n                        <div class=\"ha-flip-box-back-inner\">\n                            <div class=\"icon-wrap\">\n                                                                                            <\/div>\n\n                            <div class=\"ha-text\">\n                                                                    <h2 class=\"ha-flip-box-heading-back\">\u0456\u043d\u043e\u0437\u0435\u043c\u043d\u0456 \u0441\u043f\u0456\u043a\u0435\u0440\u0438<\/h2>\n                                \n                                                                    <p class=\"ha-desc\">\u043d\u0430\u0432\u0447\u0430\u0439\u0442\u0435\u0441\u044c \u0432 \u043a\u0440\u0430\u0449\u0438\u0445 \u0441\u043f\u0456\u043a\u0435\u0440\u0456\u0432 \u0437-\u0437\u0430 \u043a\u043e\u0440\u0434\u043e\u043d\u0443 \u0442\u0430 \u0437 \u0423\u043a\u0440\u0430\u0457\u043d\u0438 <\/p>\n                                                            <\/div>\n\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d020365 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d020365\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d1b6fd3\" data-id=\"5d1b6fd3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-966c295 elementor-widget elementor-widget-heading\" data-id=\"966c295\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0417\u0430\u0445\u0456\u0434 \u0432\u043d\u0435\u0441\u0435\u043d\u043e \u0434\u043e \u041f\u0435\u0440\u0435\u043b\u0456\u043a\u0443 \u0437\u0430\u0445\u043e\u0434\u0456\u0432 \u0411\u041f\u0420 2025 \u0440\u043e\u043a\u0443<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f68622a elementor-widget elementor-widget-heading\" data-id=\"f68622a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u041f\u0456\u0441\u043b\u044f \u0437\u0430\u0432\u0435\u0440\u0448\u0435\u043d\u043d\u044f \u0437\u0430\u0445\u043e\u0434\u0443 \u043a\u043e\u0436\u0435\u043d \u0443\u0447\u0430\u0441\u043d\u0438\u043a \u043e\u0442\u0440\u0438\u043c\u0430\u0454 \u0441\u0435\u0440\u0442\u0438\u0444\u0456\u043a\u0430\u0442 \u043f\u0440\u043e \u0443\u0447\u0430\u0441\u0442\u044c \u0443 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u0457 10 \u0431\u0430\u043b\u0456\u0432 \u0442\u0430 \u0443\u0447\u0430\u0441\u0442\u044c \u0443 \u043c\u0430\u0439\u0441\u0442\u0435\u0440-\u043a\u043b\u0430\u0441\u0456 10 \u0431\u0430\u043b\u0456\u0432 (\u0437\u0430 \u0443\u043c\u043e\u0432\u0438 \u0443\u0441\u043f\u0456\u0448\u043d\u043e\u0433\u043e \u043f\u0440\u043e\u0445\u043e\u0434\u0436\u0435\u043d\u043d\u044f \u043e\u043d\u043b\u0430\u0439\u043d-\u0442\u0435\u0441\u0442\u0443\u0432\u0430\u043d\u043d\u044f \u043f\u043e\u043d\u0430\u0434 60% \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u0438\u0445 \u0432\u0456\u0434\u043f\u043e\u0432\u0456\u0434\u0435\u0439).<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-67832fb\" data-id=\"67832fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d358f4 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"4d358f4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"#registration\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0417\u0410\u0420\u0415\u0404\u0421\u0422\u0420\u0423\u0412\u0410\u0422\u0418\u0421\u042f \u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044e<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d326755 elementor-align-right elementor-mobile-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"d326755\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/mam.net.ua\/paim\/mk20240420\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0417\u0410\u0420\u0415\u0404\u0421\u0422\u0420\u0423\u0412\u0410\u0422\u0418\u0421\u042f \u043d\u0430 \u043c\u0430\u0439\u0441\u0442\u0435\u0440-\u043a\u043b\u0430\u0441<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a14f1e5 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a14f1e5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a46b341\" data-id=\"a46b341\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-521162a elementor-widget elementor-widget-heading\" data-id=\"521162a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0426\u0456\u043b\u044c\u043e\u0432\u0430 \u0430\u0443\u0434\u0438\u0442\u043e\u0440\u0456\u044f<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4da1f5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4da1f5a\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ea6d7b5\" data-id=\"ea6d7b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-810ef4b elementor-widget elementor-widget-text-editor\" data-id=\"810ef4b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0410\u043b\u0435\u0440\u0433\u043e\u043b\u043e\u0433\u0456\u044f, \u0411\u0430\u043a\u0442\u0435\u0440\u0456\u043e\u043b\u043e\u0433\u0456\u044f, \u0412\u0456\u0440\u0443\u0441\u043e\u043b\u043e\u0433\u0456\u044f, \u0413\u0430\u0441\u0442\u0440\u043e\u0435\u043d\u0442\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u044f, \u0413\u0456\u0433\u0456\u0454\u043d\u0430 \u0434\u0456\u0442\u0435\u0439 \u0442\u0430 \u043f\u0456\u0434\u043b\u0456\u0442\u043a\u0456\u0432, \u0414\u0438\u0442\u044f\u0447\u0430 \u0430\u043b\u0435\u0440\u0433\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u0430\u043d\u0435\u0441\u0442\u0435\u0437\u0456\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u0433\u0430\u0441\u0442\u0440\u043e\u0435\u043d\u0442\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u0433\u0435\u043c\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u044f-\u043e\u043d\u043a\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u0433\u0456\u043d\u0435\u043a\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u0434\u0435\u0440\u043c\u0430\u0442\u043e\u0432\u0435\u043d\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u0435\u043d\u0434\u043e\u043a\u0440\u0438\u043d\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u0456\u043c\u0443\u043d\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u043a\u0430\u0440\u0434\u0456\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u043a\u0430\u0440\u0434\u0456\u043e\u0440\u0435\u0432\u043c\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u043d\u0435\u0432\u0440\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u043d\u0435\u0444\u0440\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u043e\u0442\u043e\u043b\u0430\u0440\u0438\u043d\u0433\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u043e\u0444\u0442\u0430\u043b\u044c\u043c\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0430 \u043f\u0443\u043b\u044c\u043c\u043e\u043d\u043e\u043b\u043e\u0433\u0456\u044f, \u0414\u0438\u0442\u044f\u0447\u0456 \u0456\u043d\u0444\u0435\u043a\u0446\u0456\u0439\u043d\u0456 \u0445\u0432\u043e\u0440\u043e\u0431\u0438, \u0414\u0456\u0454\u0442\u043e\u043b\u043e\u0433\u0456\u044f, \u0415\u043d\u0434\u043e\u043a\u0440\u0438\u043d\u043e\u043b\u043e\u0433\u0456\u044f, \u0417\u0430\u0433\u0430\u043b\u044c\u043d\u0430 \u0433\u0456\u0433\u0456\u0454\u043d\u0430, \u0417\u0430\u0433\u0430\u043b\u044c\u043d\u0430 \u043f\u0440\u0430\u043a\u0442\u0438\u043a\u0430 &#8211; \u0441\u0456\u043c\u0435\u0439\u043d\u0430 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0430, \u0406\u043d\u0444\u0435\u043a\u0446\u0456\u0439\u043d\u0456 \u0445\u0432\u043e\u0440\u043e\u0431\u0438, \u041a\u0430\u0440\u0434\u0456\u043e\u043b\u043e\u0433\u0456\u044f, \u041b\u0430\u0431\u043e\u0440\u0430\u0442\u043e\u0440\u043d\u0456 \u0434\u043e\u0441\u043b\u0456\u0434\u0436\u0435\u043d\u043d\u044f \u0444\u0430\u043a\u0442\u043e\u0440\u0456\u0432 \u043d\u0430\u0432\u043a\u043e\u043b\u0438\u0448\u043d\u044c\u043e\u0433\u043e \u0441\u0435\u0440\u0435\u0434\u043e\u0432\u0438\u0449\u0430, \u041e\u0442\u043e\u043b\u0430\u0440\u0438\u043d\u0433\u043e\u043b\u043e\u0433\u0456\u044f, \u041f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u044f, \u041f\u0443\u043b\u044c\u043c\u043e\u043d\u043e\u043b\u043e\u0433\u0456\u044f, \u0424\u0443\u043d\u043a\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u0430 \u0434\u0456\u0430\u0433\u043d\u043e\u0441\u0442\u0438\u043a\u0430, \u0422\u0435\u0440\u0430\u043f\u0456\u044f, \u041c\u0435\u0434\u0438\u043a\u043e-\u043f\u0440\u043e\u0444\u0456\u043b\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u0441\u043f\u0440\u0430\u0432\u0430, \u041b\u0456\u043a\u0443\u0432\u0430\u043b\u044c\u043d\u0430 \u0441\u043f\u0440\u0430\u0432\u0430 (\u043d\u0435\u0432\u0456\u0434\u043a\u043b\u0430\u0434\u043d\u0456 \u0441\u0442\u0430\u043d\u0438)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21d008e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21d008e\" data-element_type=\"section\" id=\"program\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4486072\" data-id=\"4486072\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac1372e elementor-widget elementor-widget-ha-gradient-heading happy-addon ha-gradient-heading\" data-id=\"ac1372e\" data-element_type=\"widget\" data-widget_type=\"ha-gradient-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"ha-gradient-heading\">\u041f\u0420\u041e\u0413\u0420\u0410\u041c\u0410<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cab5f43 elementor-widget elementor-widget-heading\" data-id=\"cab5f43\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u041d\u0430\u0443\u043a\u043e\u0432\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u0457 \u043d\u0430\u043f\u043e\u0432\u043d\u044e\u0454\u0442\u044c\u0441\u044f. <br>\u0417\u0430\u0440\u0435\u0454\u0441\u0442\u0440\u0443\u0439\u0442\u0435\u0441\u044c, \u0449\u043e\u0431 \u043f\u0435\u0440\u0448\u0438\u043c\u0438 \u043e\u0442\u0440\u0438\u043c\u0430\u0442\u0438 \u043e\u043d\u043e\u0432\u043b\u0435\u043d\u043d\u044f \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0438.  <\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-094e906 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"094e906\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/drive.google.com\/drive\/folders\/1qlY4L3ntmb2v9M0YTLE4jNI9kvduuMD7\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-google-drive\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u041f\u0440\u043e\u0433\u0440\u0430\u043c\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u0457<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-335eb89 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"335eb89\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0421\u0442\u0440\u0443\u043a\u0442\u0443\u0440\u0430 \u0437\u0430\u0445\u043e\u0434\u0443<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13826d1 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"13826d1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul>\n<li>\n<h5>18.04.24. \u041f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u044f, \u0433\u0430\u0441\u0442\u0440\u043e\u0435\u043d\u0442\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u044f, \u043d\u0435\u0432\u0440\u043e\u043b\u043e\u0433\u0456\u044f, \u0441\u0456\u043c\u0435\u0439\u043d\u0430 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0430<\/h5>\n<\/li>\n<li>\n<h5>19.04.24. \u041a\u0430\u0440\u0434\u0456\u043e\u043b\u043e\u0433\u0456\u044f, \u0433\u0430\u0441\u0442\u0440\u043e\u0435\u043d\u0442\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u044f<\/h5>\n<\/li>\n<li>\n<h5>20.04.24. \u041c\u0430\u0439\u0441\u0442\u0435\u0440-\u043a\u043b\u0430\u0441<\/h5>\n<\/li>\n<\/ul>\n<p>\u0414\u043b\u044f \u0443\u0447\u0430\u0441\u0442\u0456 \u0432 \u043c\u0430\u0439\u0441\u0442\u0435\u0440-\u043a\u043b\u0430\u0441\u0456 \u043d\u0435\u043e\u0431\u0445\u0456\u0434\u043d\u043e\u043e\u043a\u0440\u0435\u043c\u043e \u0437\u0430\u0440\u0435\u0454\u0441\u0442\u0443\u0440\u0432\u0430\u0442\u0438\u0441\u044f \u0437\u0430 \u043f\u043e\u0441\u0438\u043b\u0430\u043d\u043d\u044f\u043c: <a href=\"https:\/\/mam.net.ua\/paim\/mk20240420\">https:\/\/mam.net.ua\/paim\/mk20240420<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3332fe elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3332fe\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52272cd\" data-id=\"52272cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-798899f elementor-widget elementor-widget-ha-gradient-heading happy-addon ha-gradient-heading\" data-id=\"798899f\" data-element_type=\"widget\" id=\"partners\" data-widget_type=\"ha-gradient-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"ha-gradient-heading\">\u041f\u0410\u0420\u0422\u041d\u0415\u0420\u0418<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-697f6ca elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"697f6ca\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d9c3f44\" data-id=\"d9c3f44\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2263f72 elementor-widget elementor-widget-ha-gradient-heading happy-addon ha-gradient-heading\" data-id=\"2263f72\" data-element_type=\"widget\" data-widget_type=\"ha-gradient-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"ha-gradient-heading\">\u0421\u041f\u0406\u041a\u0415\u0420\u0418<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-41b5d94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41b5d94\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fa3aca5\" data-id=\"fa3aca5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1d2cb2 elementor-position-right elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"e1d2cb2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.3 - 07-03-2023 *\/\n.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:right;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:left;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u041b\u043e\u043f\u0443\u0445-\u0406\u0433\u043e\u0440-\u042f\u0440\u043e\u0441\u043b\u0430\u0432\u043e\u0432\u0438\u0447\u200b.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1887\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u041b\u043e\u043f\u0443\u0445-\u0406\u0433\u043e\u0440-\u042f\u0440\u043e\u0441\u043b\u0430\u0432\u043e\u0432\u0438\u0447\u200b.jpg 200w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u041b\u043e\u043f\u0443\u0445-\u0406\u0433\u043e\u0440-\u042f\u0440\u043e\u0441\u043b\u0430\u0432\u043e\u0432\u0438\u0447\u200b-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u041b\u043e\u043f\u0443\u0445 \u0406.\u042f.<\/h3><p class=\"elementor-image-box-description\">\u043a.\u043c\u0435\u0434.\u043d., \u0434\u043e\u0446\u0435\u043d\u0442 \u043a\u0430\u0444\u0435\u0434\u0440\u0438 \u0433\u0430\u0441\u0442\u0440\u043e\u0435\u043d\u0442\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u0457, \u0434\u0456\u0454\u0442\u043e\u043b\u043e\u0433\u0456\u0457 \u0456 \u0435\u043d\u0434\u043e\u0441\u043a\u043e\u043f\u0456\u0457 \u041d\u0423\u041e\u0417 \u0423\u043a\u0440\u0430\u0457\u043d\u0438 \u0456\u043c\u0435\u043d\u0456 \u041f.\u041b. \u0428\u0443\u043f\u0438\u043a\u0430<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3d3289 elementor-position-right elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"f3d3289\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0414\u0454\u0454\u0432\u0430-\u042e\u043b\u0456\u044f-\u0412\u0430\u043b\u0435\u0440\u0456\u0457\u0432\u043d\u0430.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1889\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0414\u0454\u0454\u0432\u0430-\u042e\u043b\u0456\u044f-\u0412\u0430\u043b\u0435\u0440\u0456\u0457\u0432\u043d\u0430.jpg 200w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0414\u0454\u0454\u0432\u0430-\u042e\u043b\u0456\u044f-\u0412\u0430\u043b\u0435\u0440\u0456\u0457\u0432\u043d\u0430-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0414\u0454\u0454\u0432\u0430 \u042e.\u0412.<\/h3><p class=\"elementor-image-box-description\">\u0434\u043e\u043a\u0442\u043e\u0440 \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0445 \u043d\u0430\u0443\u043a, \u043f\u0440\u043e\u0444\u0435\u0441\u043e\u0440, \u0437\u0430\u0432\u0456\u0434\u0443\u0432\u0430\u0447 \u043a\u0430\u0444\u0435\u0434\u0440\u0438 \u043e\u0442\u043e\u0440\u0438\u043d\u043e\u043b\u0430\u0440\u0438\u043d\u0433\u043e\u043b\u043e\u0433\u0456\u0457 \u041d\u0430\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u043c\u0435\u0434\u0438\u0447\u043d\u043e\u0433\u043e \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442\u0443 \u0456\u043c\u0435\u043d\u0456 \u041e.\u041e.\u0411\u043e\u0433\u043e\u043c\u043e\u043b\u044c\u0446\u044f<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faed5c0 elementor-position-right elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"faed5c0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0422\u0440\u0438\u043f\u0456\u043b\u043a\u0430-\u0421\u0432\u0456\u0442\u043b\u0430\u043d\u0430-\u0410\u043d\u0430\u0442\u043e\u043b\u0456\u0457\u0432\u043d\u0430.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1894\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0422\u0440\u0438\u043f\u0456\u043b\u043a\u0430-\u0421\u0432\u0456\u0442\u043b\u0430\u043d\u0430-\u0410\u043d\u0430\u0442\u043e\u043b\u0456\u0457\u0432\u043d\u0430.jpg 200w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0422\u0440\u0438\u043f\u0456\u043b\u043a\u0430-\u0421\u0432\u0456\u0442\u043b\u0430\u043d\u0430-\u0410\u043d\u0430\u0442\u043e\u043b\u0456\u0457\u0432\u043d\u0430-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0422\u0440\u0438\u043f\u0456\u043b\u043a\u0430 \u0421.\u0410.<\/h3><p class=\"elementor-image-box-description\">\u041b\u0456\u043a\u0430\u0440-\u0440\u0435\u0432\u043c\u0430\u0442\u043e\u043b\u043e\u0433, \u043a\u0430\u043d\u0434\u0438\u0434\u0430\u0442 \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0445 \u043d\u0430\u0443\u043a, \u0434\u043e\u0446\u0435\u043d\u0442<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1696001 elementor-position-right elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"1696001\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0411\u043e\u043d\u0434\u0430\u0440\u0435\u043d\u043a\u043e \u041e.\u041e.<\/h3><p class=\"elementor-image-box-description\">\u043f\u0440\u043e\u0444\u0435\u0441\u043e\u0440 \u043a\u0430\u0444\u0435\u0434\u0440\u0438 \u0442\u0435\u0440\u0430\u043f\u0456\u0457 No1, \u043c\u0435\u0434\u0438\u0447\u043d\u043e\u0457 \u0434\u0456\u0430\u0433\u043d\u043e\u0441\u0442\u0438\u043a\u0438 \u0442\u0430 \u0433\u0435\u043c\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u0457 \u0456 \u0442\u0440\u0430\u043d\u0441\u0444\u0443\u0437\u0456\u043e\u043b\u043e\u0433\u0456\u0457 \u0424\u041f\u0414\u041e \u041b\u044c\u0432\u0456\u0432\u0441\u044c\u043a\u043e\u0433\u043e \u043d\u0430\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u043c\u0435\u0434\u0438\u0447\u043d\u043e\u0433\u043e \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442\u0443 \u0456\u043c\u0435\u043d\u0456 \u0414\u0430\u043d\u0438\u043b\u0430 \u0413\u0430\u043b\u0438\u0446\u044c\u043a\u043e\u0433\u043e, \u0434\u043e\u043a\u0442\u043e\u0440 \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0445 \u043d\u0430\u0443\u043a<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4178a9 elementor-position-right elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"a4178a9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0422\u0440\u043e\u0446\u044c\u043a\u0438\u0439-\u0413\u0440\u0438\u0433\u043e\u0440\u0456\u0439-\u041c\u0438\u0445\u0430\u0439\u043b\u043e\u0432\u0438\u0447\u200b.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1891\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0422\u0440\u043e\u0446\u044c\u043a\u0438\u0439-\u0413\u0440\u0438\u0433\u043e\u0440\u0456\u0439-\u041c\u0438\u0445\u0430\u0439\u043b\u043e\u0432\u0438\u0447\u200b.jpg 200w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0422\u0440\u043e\u0446\u044c\u043a\u0438\u0439-\u0413\u0440\u0438\u0433\u043e\u0440\u0456\u0439-\u041c\u0438\u0445\u0430\u0439\u043b\u043e\u0432\u0438\u0447\u200b-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0422\u0440\u043e\u0446\u044c\u043a\u0438\u0439 \u0413.\u041c.<\/h3><p class=\"elementor-image-box-description\">\u043a.\u043c\u0435\u0434.\u043d., \u0434\u043e\u0446.\u043a\u0430\u0444.\u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457 \u0456 \u043d\u0435\u043e\u043d\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u0457 \u0424\u041f\u0414\u041e \u041b\u041d\u041c\u0423 \u0456\u043c.\u0414.\u0413\u0430\u043b\u0438\u0446\u044c\u043a\u043e\u0433\u043e, \u043a\u0430\u043f\u0456\u0442\u0430\u043d \u043c\u0435\u0434\u0438\u0447\u043d\u043e\u0457 \u0441\u043b\u0443\u0436\u0431\u0438 66 \u041e\u041c\u0413<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59f7f54 elementor-position-right elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"59f7f54\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0421\u043b\u0456\u0432\u0456\u043d\u0441\u044c\u043a\u0430-\u041a\u0443\u0440\u0447\u0430\u043a-\u0425\u0440\u0438\u0441\u0442\u0438\u043d\u0430-\u0411\u043e\u0433\u0434\u0430\u043d\u0456\u0432\u043d\u0430\u200b.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1892\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0421\u043b\u0456\u0432\u0456\u043d\u0441\u044c\u043a\u0430-\u041a\u0443\u0440\u0447\u0430\u043a-\u0425\u0440\u0438\u0441\u0442\u0438\u043d\u0430-\u0411\u043e\u0433\u0434\u0430\u043d\u0456\u0432\u043d\u0430\u200b.jpg 200w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0421\u043b\u0456\u0432\u0456\u043d\u0441\u044c\u043a\u0430-\u041a\u0443\u0440\u0447\u0430\u043a-\u0425\u0440\u0438\u0441\u0442\u0438\u043d\u0430-\u0411\u043e\u0433\u0434\u0430\u043d\u0456\u0432\u043d\u0430\u200b-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0421\u043b\u0456\u0432\u0456\u043d\u0441\u044c\u043a\u0430-\u041a\u0443\u0440\u0447\u0430\u043a \u0425. \u0411.<\/h3><p class=\"elementor-image-box-description\">\u043b\u0456\u043a\u0430\u0440-\u043a\u0430\u0440\u0434\u0456\u043e\u0440\u0435\u0432\u043c\u0430\u0442\u043e\u043b\u043e\u0433 \u0434\u0438\u0442\u044f\u0447\u0438\u0439, \u043b\u0456\u043a\u0430\u0440 \u0437 \u0444\u0443\u043d\u043a\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u043e\u0457 \u0434\u0456\u0430\u0433\u043d\u043e\u0441\u0442\u0438\u043a\u0438, \u043a\u0430\u043d\u0434\u0438\u0434\u0430\u0442 \u043c\u0435\u0434 \u043d\u0430\u0443\u043a, \u0430\u0441\u0438\u0441\u0442\u0435\u043d\u0442 \u043a\u0430\u0444\u0435\u0434\u0440\u0438 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457 \u0456 \u043d\u0435\u043e\u043d\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u0457, \u0447\u043b\u0435\u043d\u043a\u0438\u043d\u044f \u0423\u043a\u0440\u0430\u0457\u043d\u0441\u044c\u043a\u043e\u0457, \u0410\u0441\u043e\u0446\u0456\u0430\u0446\u0456\u0457 \u0414\u0438\u0442\u044f\u0447\u043e\u0457 \u041a\u0430\u0440\u0434\u0456\u043e\u043b\u043e\u0433\u0456\u0457 \u0456 EHRA (European Heart Rhythm Association)<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1488a62 elementor-position-right elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"1488a62\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0411\u043e\u0433\u043e\u043c\u043e\u043b\u043e\u0432 \u0410\u0440\u0442\u0435\u043c\u0456\u0439 \u0404\u0432\u0433\u0435\u043d\u043e\u0432\u0438\u0447<\/h3><p class=\"elementor-image-box-description\">\u0434.\u043c\u0435\u0434.\u043d., \u0434\u043e\u0446\u0435\u043d\u0442 \u043a\u0430\u0444\u0435\u0434\u0440\u0438 \u0444\u0442\u0438\u0437\u0456\u0430\u0442\u0440\u0456\u0457 \u0437 \u043a\u0443\u0440\u0441\u043e\u043c \u043a\u043b\u0456\u043d\u0456\u0447\u043d\u043e\u0457 \u0456\u043c\u0443\u043d\u043e\u043b\u043e\u0433\u0456\u0457 \u0442\u0430 \u0430\u043b\u0435\u0440\u0433\u043e\u043b\u043e\u0433\u0456\u0457 \u0412\u0456\u043d\u043d\u0438\u0446\u044c\u043a\u043e\u0433\u043e \u043d\u0430\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u043c\u0435\u0434\u0438\u0447\u043d\u043e\u0433\u043e \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442\u0443 \u0456\u043c. \u041c.\u0406.\u041f\u0438\u0440\u043e\u0433\u043e\u0432\u0430\n<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e9511cc\" data-id=\"e9511cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d83e96 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"8d83e96\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0404\u0433\u0443\u0434\u0456\u043d\u0430-\u0404\u043b\u0438\u0437\u0430\u0432\u0435\u0442\u0430-\u0414\u0430\u0432\u0438\u0434\u0456\u0432\u043d\u0430.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1888\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0404\u0433\u0443\u0434\u0456\u043d\u0430-\u0404\u043b\u0438\u0437\u0430\u0432\u0435\u0442\u0430-\u0414\u0430\u0432\u0438\u0434\u0456\u0432\u043d\u0430.jpg 200w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0404\u0433\u0443\u0434\u0456\u043d\u0430-\u0404\u043b\u0438\u0437\u0430\u0432\u0435\u0442\u0430-\u0414\u0430\u0432\u0438\u0434\u0456\u0432\u043d\u0430-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0404\u0433\u0443\u0434\u0456\u043d\u0430 \u0404.\u0414.<\/h3><p class=\"elementor-image-box-description\">\u0434\u043e\u043a\u0442\u043e\u0440 \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0445 \u043d\u0430\u0443\u043a, \u0440\u0435\u0432\u043c\u0430\u0442\u043e\u043b\u043e\u0433, \u043a\u0435\u0440\u0456\u0432\u043d\u0438\u043a \u043d\u0430\u0432\u0447\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u0446\u0435\u043d\u0442\u0440\u0443 \u00ab\u0406\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u0440\u0435\u0432\u043c\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u0457\u00bb<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7327b5e elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"7327b5e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u041a\u043e\u043b\u0435\u0441\u043d\u0438\u043a-\u041f\u0430\u0432\u043b\u043e-\u041e\u043b\u0435\u0433\u043e\u0432\u0438\u0447.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1893\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u041a\u043e\u043b\u0435\u0441\u043d\u0438\u043a-\u041f\u0430\u0432\u043b\u043e-\u041e\u043b\u0435\u0433\u043e\u0432\u0438\u0447.jpg 200w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u041a\u043e\u043b\u0435\u0441\u043d\u0438\u043a-\u041f\u0430\u0432\u043b\u043e-\u041e\u043b\u0435\u0433\u043e\u0432\u0438\u0447-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u041a\u043e\u043b\u0435\u0441\u043d\u0438\u043a \u041f.\u041e.<\/h3><p class=\"elementor-image-box-description\">\u041a\u0430\u043d\u0434\u0438\u0434\u0430\u0442 \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0445 \u043d\u0430\u0443\u043a, \u0434\u043e\u0446\u0435\u043d\u0442, \u0437\u0430\u0432\u0456\u0434\u0443\u0432\u0430\u0447  \u043a\u0430\u0444\u0435\u0434\u0440\u0438 \u0441\u0456\u043c\u0435\u0439\u043d\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 \u0442\u0430 \u0430\u043c\u0431\u0443\u043b\u0430\u0442\u043e\u0440\u043d\u043e\u0457 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0438, \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0439 \u0444\u0430\u043a\u0443\u043b\u044c\u0442\u0435\u0442 \u21162, \u0423\u0436\u0433\u043e\u0440\u043e\u0434\u0441\u044c\u043a\u0438\u0439 \u043d\u0430\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u0438\u0439 \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442, \u0434\u0438\u0440\u0435\u043a\u0442\u043e\u0440 \u043d\u0430\u0432\u0447\u0430\u043b\u044c\u043d\u043e-\u043d\u0430\u0443\u043a\u043e\u0432\u043e\u0433\u043e \u0442\u0440\u0435\u043d\u0456\u043d\u0433\u043e\u0432\u043e\u0433\u043e \u0426\u0435\u043d\u0442\u0440\u0443 \u0441\u0456\u043c\u0435\u0439\u043d\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 \u0442\u0430 \u0434\u043e\u043b\u0456\u043a\u0430\u0440\u0441\u044c\u043a\u043e\u0457 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0438 \u0424\u041f\u041e \u0423\u0436\u0433\u043e\u0440\u043e\u0434\u0441\u044c\u043a\u043e\u0433\u043e \u043d\u0430\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442\u0443<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a02825b elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"a02825b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u041f\u043e\u0442\u0430\u0431\u0430\u0448\u043d\u0456\u0439-\u0412\u0430\u043b\u0435\u0440\u0456\u0439-\u0410\u0440\u043a\u0430\u0434\u0456\u0439\u043e\u0432\u0438\u0447.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1895\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u041f\u043e\u0442\u0430\u0431\u0430\u0448\u043d\u0456\u0439-\u0412\u0430\u043b\u0435\u0440\u0456\u0439-\u0410\u0440\u043a\u0430\u0434\u0456\u0439\u043e\u0432\u0438\u0447.jpg 200w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u041f\u043e\u0442\u0430\u0431\u0430\u0448\u043d\u0456\u0439-\u0412\u0430\u043b\u0435\u0440\u0456\u0439-\u0410\u0440\u043a\u0430\u0434\u0456\u0439\u043e\u0432\u0438\u0447-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u041f\u043e\u0442\u0430\u0431\u0430\u0448\u043d\u0456\u0439 \u0412.\u0410.<\/h3><p class=\"elementor-image-box-description\">\u0414.\u043c\u0435\u0434.\u043d., \u043f\u0440\u043e\u0444\u0435\u0441\u043e\u0440, \u0437\u0430\u0432\u0456\u0434\u0443\u0432\u0430\u0447 \u043a\u0430\u0444\u0435\u0434\u0440\u0438 \u043a\u0430\u0444\u0435\u0434\u0440\u0438 \u0442\u0435\u0440\u0430\u043f\u0456\u0457, \u043a\u0430\u0440\u0434\u0456\u043e\u043b\u043e\u0433\u0456\u0457 \u0442\u0430 \u0441\u0456\u043c\u0435\u0439\u043d\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 \u0424\u041f\u041e \u0414\u043d\u0456\u043f\u0440\u043e\u0432\u0441\u044c\u043a\u043e\u0433\u043e \u0434\u0435\u0440\u0436\u0430\u0432\u043d\u043e\u0433\u043e \u043c\u0435\u0434\u0438\u0447\u043d\u043e\u0433\u043e \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442\u0443<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2b659b elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"d2b659b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0428\u0432\u0435\u0446\u044c-\u041e\u043b\u0435\u0433-\u0412\u0456\u0442\u0430\u043b\u0456\u0439\u043e\u0432\u0438\u0447.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1890\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0428\u0432\u0435\u0446\u044c-\u041e\u043b\u0435\u0433-\u0412\u0456\u0442\u0430\u043b\u0456\u0439\u043e\u0432\u0438\u0447.jpg 200w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0428\u0432\u0435\u0446\u044c-\u041e\u043b\u0435\u0433-\u0412\u0456\u0442\u0430\u043b\u0456\u0439\u043e\u0432\u0438\u0447-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0428\u0432\u0435\u0446\u044c \u041e.\u0412.<\/h3><p class=\"elementor-image-box-description\">\u043a.\u043c\u0435\u0434.\u043d., \u043f\u0440\u043e\u0444\u0435\u0441\u043e\u0440, \u043f\u0440\u0435\u0437\u0438\u0434\u0435\u043d\u0442 \u0412\u0413\u041e \u00ab\u0414\u0441\u043e\u0446\u0456\u0430\u0446\u0456\u044f \u0434\u0456\u0454\u0442\u043e\u043b\u043e\u0433\u0456\u0432 \u0443\u043a\u0440\u0430\u0457\u043d\u0438\u00bb, \u0447\u043b\u0435\u043d \u043f\u0440\u0435\u0437\u0438\u0434\u0456\u0457 \u0413\u041e \u00ab\u0423\u043a\u0440\u0430\u0457\u043d\u0441\u044c\u043a\u0430 \u0433\u0430\u0441\u0442\u0440\u043e\u0435\u043d\u0442\u0435\u0440\u043e\u043b\u043e\u0433\u0456\u0447\u043d\u0430 \u0430\u0441\u043e\u0446\u0456\u0430\u0446\u0456\u044f\u00bb<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25e2186 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"25e2186\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0410\u0440\u0442\u0443\u0440 \u041c\u0430\u0437\u0443\u0440  <\/h3><p class=\"elementor-image-box-description\">\u041f\u0440\u043e\u0444\u0435\u0441\u043e\u0440, \u043f\u0440\u043e\u0440\u0435\u043a\u0442\u043e\u0440 \u0416\u0435\u0448\u0443\u0432\u0441\u044c\u043a\u043e\u0433\u043e \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442\u0443, \u041f\u043e\u043b\u044c\u0449\u0430<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e235c61 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"e235c61\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0411\u0454\u043b\u043e\u0443\u0441\u043e\u0432\u0430 \u041e\u043b\u044c\u0433\u0430 \u042e\u0440\u0456\u0457\u0432\u043d\u0430<\/h3><p class=\"elementor-image-box-description\">\u0434.\u043c\u0435\u0434.\u043d., \u043f\u0440\u043e\u0444\u0435\u0441\u043e\u0440, \u0437\u0430\u0432\u0456\u0434\u0443\u0432\u0430\u0447 \u043a\u0430\u0444\u0435\u0434\u0440\u0438 \u043f\u0435\u0434\u0456\u0430\u0442\u0440\u0456\u0457 \u0442\u0430 \u043d\u0435\u043e\u043d\u0430\u0442\u043e\u043b\u043e\u0433\u0456\u0457 \u21163 \u041d\u041d\u0406 \u0425\u0430\u0440\u043a\u0456\u0432\u0441\u044c\u043a\u043e\u0433\u043e \u043d\u0430\u0446\u0456\u043e\u043d\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u043c\u0435\u0434\u0438\u0447\u043d\u043e\u0433\u043e \u0443\u043d\u0456\u0432\u0435\u0440\u0441\u0438\u0442\u0435\u0442\u0443, \u0433\u043e\u043b\u043e\u0432\u0430 \u043a\u043e\u043c\u0456\u0442\u0435\u0442\u0443 \u0421\u043f\u0435\u0446\u0456\u0430\u043b\u0456\u0437\u043e\u0432\u0430\u043d\u043e\u0457 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0438 \u0434\u0456\u0442<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09657f4 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"09657f4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0411\u043e\u0433\u043e\u043c\u043e\u043b\u043e\u0432-\u0410\u0440\u0442\u0435\u043c\u0456\u0439-\u0404\u0432\u0433\u0435\u043d\u043e\u0432\u0438\u0447.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1906\" alt=\"\" srcset=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0411\u043e\u0433\u043e\u043c\u043e\u043b\u043e\u0432-\u0410\u0440\u0442\u0435\u043c\u0456\u0439-\u0404\u0432\u0433\u0435\u043d\u043e\u0432\u0438\u0447.jpg 200w, https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2024\/04\/\u0411\u043e\u0433\u043e\u043c\u043e\u043b\u043e\u0432-\u0410\u0440\u0442\u0435\u043c\u0456\u0439-\u0404\u0432\u0433\u0435\u043d\u043e\u0432\u0438\u0447-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0411\u0443\u0440\u0447\u0438\u043d\u0441\u044c\u043a\u0438\u0439 \u0421\u0435\u0440\u0433\u0456\u0439 \u0413\u0435\u043e\u0440\u0433\u0456\u0439\u043e\u0432\u0438\u0447<\/h3><p class=\"elementor-image-box-description\">\u043a.\u043c\u0435\u0434.\u043d., \u043a\u0435\u0440\u0456\u0432\u043d\u0438\u043a \u0432\u0456\u0434\u0434\u0456\u043b\u0443 \u0456\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0456\u0439\u043d\u043e\u0433\u043e \u0430\u043d\u0430\u043b\u0456\u0437\u0443 \u0442\u0430 \u043c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u0438\u0445 \u043d\u0430\u0443\u043a\u043e\u0432\u0438\u0445 \u043f\u0440\u043e\u0433\u0440\u0430\u043c \u0406\u043d\u0441\u0442\u0438\u0442\u0443\u0442\u0443 \u0433\u0435\u0440\u043e\u043d\u0442\u043e\u043b\u043e\u0433\u0456\u0457 \u0456\u043c. \u0414.\u0424. \u0427\u0435\u0431\u043e\u0442\u0430\u0440\u044c\u043e\u0432\u0430 \u041d\u0410\u041c\u041d \u0423\u043a\u0440\u0430\u0457\u043d\u0438<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f9bbf1a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f9bbf1a\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31150df\" data-id=\"31150df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1c4f8f elementor-widget elementor-widget-ha-gradient-heading happy-addon ha-gradient-heading\" data-id=\"b1c4f8f\" data-element_type=\"widget\" id=\"registration\" data-widget_type=\"ha-gradient-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"ha-gradient-heading\">\u0420\u0415\u0404\u0421\u0422\u0420\u0410\u0426\u0406\u042f<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f69e81 elementor-widget elementor-widget-ha-gradient-heading happy-addon ha-gradient-heading\" data-id=\"8f69e81\" data-element_type=\"widget\" data-widget_type=\"ha-gradient-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"ha-gradient-heading\">\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044e<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b943290 elementor-widget elementor-widget-html\" data-id=\"b943290\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<iframe src=\"https:\/\/video.e-registration.com.ua\/viewers\/new?event=8980259\" style=\"width:100%; height:1200px\"><\/iframe>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25cece2 elementor-widget elementor-widget-text-editor\" data-id=\"25cece2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"qodef-m-content\"><p class=\"qodef-m-title\">\u042f\u043a\u0449\u043e \u043d\u0430 \u0412\u0430\u0448\u043e\u043c\u0443 \u043f\u0440\u0438\u0441\u0442\u0440\u043e\u0457 \u043d\u0435 \u0432\u0456\u0434\u043e\u0431\u0440\u0430\u0436\u0443\u0454\u0442\u044c\u0441\u044f \u0444\u043e\u0440\u043c\u0430, \u043d\u0430\u0442\u0438\u0441\u043d\u0456\u0442\u044c \u043a\u043d\u043e\u043f\u043a\u0443<\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76fa5bd elementor-align-left elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"76fa5bd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/video.e-registration.com.ua\/viewers\/new?event=8980259&#038;utm_content=ereg\" class=\"elementor-button-link elementor-button elementor-size-xl elementor-animation-grow\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0412\u0456\u0434\u043a\u0440\u0438\u0442\u0438 \u0444\u043e\u0440\u043c\u0443<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0437 \u043c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u044e \u0443\u0447\u0430\u0441\u0442\u044e \u041f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 23-24 \u043a\u0432\u0456\u0442\u043d\u044f 2025 \u0440\u043e\u043a\u0443 | \u041e\u043d\u043b\u0430\u0439\u043d \u0417\u0410\u0420\u0415\u0404\u0421\u0422\u0420\u0423\u0412\u0410\u0422\u0418\u0421\u042f \u041e\u0420\u0413\u0410\u041d\u0406\u0417\u0410\u0422\u041e\u0420\u0418 \u041d\u0410\u0423\u041a\u041e\u0412\u0418\u0419 \u041a\u041e\u041c\u0406\u0422\u0415\u0422 \u041d\u042f\u041d\u042c\u041a\u041e\u0412\u0421\u042c\u041a\u0418\u0419 \u0421\u0435\u0440\u0433\u0456\u0439 \u041b\u0435\u043e\u043d\u0456\u0434\u043e\u0432\u0438\u0447 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1938,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/page_front-page.php","meta":{"footnotes":""},"class_list":["post-1928","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u041f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 - 2025<\/title>\n<meta name=\"description\" content=\"\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0437 \u043c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u044e \u0443\u0447\u0430\u0441\u0442\u044e, 23-24 \u043a\u0432\u0456\u0442\u043d\u044f 2025 \u0440\u043e\u043a\u0443, \u041e\u043d\u043b\u0430\u0439\u043d. 10 \u0431\u0430\u043b\u0456\u0432 \u0411\u041f\u0420\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mam.net.ua\/paim\/conference2025\/\" \/>\n<meta property=\"og:locale\" content=\"uk_UA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u041f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 - 2025\" \/>\n<meta property=\"og:description\" content=\"\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0437 \u043c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u044e \u0443\u0447\u0430\u0441\u0442\u044e, 23-24 \u043a\u0432\u0456\u0442\u043d\u044f 2025 \u0440\u043e\u043a\u0443, \u041e\u043d\u043b\u0430\u0439\u043d. 10 \u0431\u0430\u043b\u0456\u0432 \u0411\u041f\u0420\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mam.net.ua\/paim\/conference2025\/\" \/>\n<meta property=\"og:site_name\" content=\"\u041f\u0440\u0430\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-18T08:46:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/03\/2025.04.23.-MAM-PAIM-banner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u0431\u043b. \u0447\u0430\u0441 \u0447\u0438\u0442\u0430\u043d\u043d\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 \u0445\u0432\u0438\u043b\u0438\u043d\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mam.net.ua\/paim\/conference2025\/\",\"url\":\"https:\/\/mam.net.ua\/paim\/conference2025\/\",\"name\":\"\u041f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 - 2025\",\"isPartOf\":{\"@id\":\"https:\/\/mam.net.ua\/paim\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mam.net.ua\/paim\/conference2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mam.net.ua\/paim\/conference2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/03\/2025.04.23.-MAM-PAIM-banner.jpg\",\"datePublished\":\"2025-03-17T21:12:58+00:00\",\"dateModified\":\"2025-04-18T08:46:35+00:00\",\"description\":\"\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0437 \u043c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u044e \u0443\u0447\u0430\u0441\u0442\u044e, 23-24 \u043a\u0432\u0456\u0442\u043d\u044f 2025 \u0440\u043e\u043a\u0443, \u041e\u043d\u043b\u0430\u0439\u043d. 10 \u0431\u0430\u043b\u0456\u0432 \u0411\u041f\u0420\",\"breadcrumb\":{\"@id\":\"https:\/\/mam.net.ua\/paim\/conference2025\/#breadcrumb\"},\"inLanguage\":\"uk\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mam.net.ua\/paim\/conference2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"uk\",\"@id\":\"https:\/\/mam.net.ua\/paim\/conference2025\/#primaryimage\",\"url\":\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/03\/2025.04.23.-MAM-PAIM-banner.jpg\",\"contentUrl\":\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/03\/2025.04.23.-MAM-PAIM-banner.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mam.net.ua\/paim\/conference2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043e\u043b\u043e\u0432\u043d\u0430\",\"item\":\"https:\/\/mam.net.ua\/paim\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 &#8211; 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mam.net.ua\/paim\/#website\",\"url\":\"https:\/\/mam.net.ua\/paim\/\",\"name\":\"\u041f\u0440\u0430\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/mam.net.ua\/paim\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mam.net.ua\/paim\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"uk\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mam.net.ua\/paim\/#organization\",\"name\":\"\u041f\u0440\u0430\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438\",\"url\":\"https:\/\/mam.net.ua\/paim\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"uk\",\"@id\":\"https:\/\/mam.net.ua\/paim\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/logo-1.png\",\"contentUrl\":\"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/logo-1.png\",\"width\":231,\"height\":80,\"caption\":\"\u041f\u0440\u0430\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438\"},\"image\":{\"@id\":\"https:\/\/mam.net.ua\/paim\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 - 2025","description":"\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0437 \u043c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u044e \u0443\u0447\u0430\u0441\u0442\u044e, 23-24 \u043a\u0432\u0456\u0442\u043d\u044f 2025 \u0440\u043e\u043a\u0443, \u041e\u043d\u043b\u0430\u0439\u043d. 10 \u0431\u0430\u043b\u0456\u0432 \u0411\u041f\u0420","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mam.net.ua\/paim\/conference2025\/","og_locale":"uk_UA","og_type":"article","og_title":"\u041f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 - 2025","og_description":"\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0437 \u043c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u044e \u0443\u0447\u0430\u0441\u0442\u044e, 23-24 \u043a\u0432\u0456\u0442\u043d\u044f 2025 \u0440\u043e\u043a\u0443, \u041e\u043d\u043b\u0430\u0439\u043d. 10 \u0431\u0430\u043b\u0456\u0432 \u0411\u041f\u0420","og_url":"https:\/\/mam.net.ua\/paim\/conference2025\/","og_site_name":"\u041f\u0440\u0430\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438","article_modified_time":"2025-04-18T08:46:35+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/03\/2025.04.23.-MAM-PAIM-banner.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u0431\u043b. \u0447\u0430\u0441 \u0447\u0438\u0442\u0430\u043d\u043d\u044f":"8 \u0445\u0432\u0438\u043b\u0438\u043d"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mam.net.ua\/paim\/conference2025\/","url":"https:\/\/mam.net.ua\/paim\/conference2025\/","name":"\u041f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 - 2025","isPartOf":{"@id":"https:\/\/mam.net.ua\/paim\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mam.net.ua\/paim\/conference2025\/#primaryimage"},"image":{"@id":"https:\/\/mam.net.ua\/paim\/conference2025\/#primaryimage"},"thumbnailUrl":"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/03\/2025.04.23.-MAM-PAIM-banner.jpg","datePublished":"2025-03-17T21:12:58+00:00","dateModified":"2025-04-18T08:46:35+00:00","description":"\u041d\u0430\u0443\u043a\u043e\u0432\u043e-\u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0430 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0456\u044f \u0437 \u043c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u044e \u0443\u0447\u0430\u0441\u0442\u044e, 23-24 \u043a\u0432\u0456\u0442\u043d\u044f 2025 \u0440\u043e\u043a\u0443, \u041e\u043d\u043b\u0430\u0439\u043d. 10 \u0431\u0430\u043b\u0456\u0432 \u0411\u041f\u0420","breadcrumb":{"@id":"https:\/\/mam.net.ua\/paim\/conference2025\/#breadcrumb"},"inLanguage":"uk","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mam.net.ua\/paim\/conference2025\/"]}]},{"@type":"ImageObject","inLanguage":"uk","@id":"https:\/\/mam.net.ua\/paim\/conference2025\/#primaryimage","url":"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/03\/2025.04.23.-MAM-PAIM-banner.jpg","contentUrl":"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2025\/03\/2025.04.23.-MAM-PAIM-banner.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/mam.net.ua\/paim\/conference2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043e\u043b\u043e\u0432\u043d\u0430","item":"https:\/\/mam.net.ua\/paim\/"},{"@type":"ListItem","position":2,"name":"\u041f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438 &#8211; 2025"}]},{"@type":"WebSite","@id":"https:\/\/mam.net.ua\/paim\/#website","url":"https:\/\/mam.net.ua\/paim\/","name":"\u041f\u0440\u0430\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438","description":"","publisher":{"@id":"https:\/\/mam.net.ua\/paim\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mam.net.ua\/paim\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"uk"},{"@type":"Organization","@id":"https:\/\/mam.net.ua\/paim\/#organization","name":"\u041f\u0440\u0430\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438","url":"https:\/\/mam.net.ua\/paim\/","logo":{"@type":"ImageObject","inLanguage":"uk","@id":"https:\/\/mam.net.ua\/paim\/#\/schema\/logo\/image\/","url":"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/logo-1.png","contentUrl":"https:\/\/mam.net.ua\/paim\/wp-content\/uploads\/2023\/03\/logo-1.png","width":231,"height":80,"caption":"\u041f\u0440\u0430\u0442\u0438\u0447\u043d\u0456 \u0430\u0441\u043f\u0435\u043a\u0442\u0438 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u0457 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0438"},"image":{"@id":"https:\/\/mam.net.ua\/paim\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mam.net.ua\/paim\/wp-json\/wp\/v2\/pages\/1928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mam.net.ua\/paim\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mam.net.ua\/paim\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mam.net.ua\/paim\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mam.net.ua\/paim\/wp-json\/wp\/v2\/comments?post=1928"}],"version-history":[{"count":10,"href":"https:\/\/mam.net.ua\/paim\/wp-json\/wp\/v2\/pages\/1928\/revisions"}],"predecessor-version":[{"id":1948,"href":"https:\/\/mam.net.ua\/paim\/wp-json\/wp\/v2\/pages\/1928\/revisions\/1948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mam.net.ua\/paim\/wp-json\/wp\/v2\/media\/1938"}],"wp:attachment":[{"href":"https:\/\/mam.net.ua\/paim\/wp-json\/wp\/v2\/media?parent=1928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}